{"id":104868,"date":"2024-04-24T10:38:25","date_gmt":"2024-04-24T08:38:25","guid":{"rendered":"https:\/\/startupvalley.news\/de\/?p=104868"},"modified":"2026-06-11T08:27:43","modified_gmt":"2026-06-11T06:27:43","slug":"surfbank","status":"publish","type":"post","link":"https:\/\/startupvalley.news\/de\/surfbank\/","title":{"rendered":"Verwalten Sie Ihre digitalen Inhalte m\u00fchelos"},"content":{"rendered":"\n<h2 class=\"wp-block-heading\">SURFBANK ist ein innovatives Unternehmen, das eine Plattform entwickelt hat, um pers\u00f6nliche Inhalte wie Artikel, Links und Medien in einer zentralisierten Medienbibliothek zu organisieren und zu teilen, wodurch Nutzer einfach auf relevante Informationen zugreifen und diese mit anderen austauschen k\u00f6nnen<\/h2>\n\n\n\n<h4 class=\"wp-block-heading\">K\u00f6nnen Sie uns einen kurzen \u00dcberblick \u00fcber die Entstehung von SURFBANK geben und die Schl\u00fcsselpersonen vorstellen, die hinter diesem Projekt stehen?\u00a0<\/h4>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Benjamin Syring:&nbsp;<\/strong>&nbsp;Alles auf einen Blick: Was hat mich dazu inspiriert, SURFBANK zu gr\u00fcnden?&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ich war \u00fcber 22 Jahre im Marketingbereich eines gro\u00dfen Automobilkonzerns in vielf\u00e4ltigen Funktionen t\u00e4tig und hatte in den letzten Jahren viel mit den Themen digitaler Customer Experience und Content Management zu tun. &nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Pers\u00f6nlich haben mich schon immer Menschen inspiriert, die \u00fcber eine innere Unabh\u00e4ngigkeit verf\u00fcgen und ihrem inneren Antrieb, ihrer Motivationen und Leidenschaften nachgehen, mit einem klaren Ziel vor Augen. Das sind die verr\u00fcckten Snowboarder, die die steilsten H\u00e4nge oder dichte W\u00e4lder befahren, Surfer auf der Suche nach der perfekten Welle in der Arktis, Pers\u00f6nlichkeiten wie William McRaven, der die ber\u00fchmte \u201e<em>Make-your-Bed<\/em>\u201c-Rede h\u00e4lt, der Big-Wave-Surfer Gareth McNamara, Reinhold Messner und die unglaubliche Expedition von Ernest Shackleton zum S\u00fcdpol.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Alles, was ich dazu finden konnte, wollte ich digital behalten, speichern und anschauen, wenn ich es wollte. Gleicherma\u00dfen habe ich gemerkt, dass ich an unterschiedlichen Stellen meine Favoriten abgelegt hatte:&nbsp; als Bookmark im Browser, in Apps, als Screenshots auf dem Smartphone oder in Ordnern auf meinem Computer, offenen Tabs, usw. Man switcht heutzutage von App zu App und beh\u00e4lt kaum mehr den \u00dcberblick.&nbsp;&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Mein Wunsch war, all dies f\u00fcr mich an einem Ort zug\u00e4nglich zu machen, eine Art pers\u00f6nliche \u201eSocial Wall\u2018 f\u00fcr meine Favoriten. Daraus entstand die Idee, die Kernfunktionalit\u00e4t und der Name SURFBANK: eine <a href=\"https:\/\/startupvalley.news\/de\/?s=app\" target=\"_blank\" rel=\"noreferrer noopener\">App<\/a>, in der ich meine Favoriten, meine \u201edigitalen Perlen\u201c die ich beim \u201eSurfen\u201c finde, in meiner Medienbibliothek speichern und in meinen eigenen Ordnern leicht wiederfinden kann.\u00a0<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Die Idee wurde zun\u00e4chst im engsten Freundeskreis und der Familie getestet. Das Gr\u00fcnderteam, bestehend aus langj\u00e4hrigen Freunden und Experten auf den Gebieten IT\/Systeme mit Oliver Rudolph und Finanzen mit Ingo Fr\u00f6hlich, hat sich schnell formiert.&nbsp;&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>I<\/strong>nspiriert von Streaming-Plattformen und Mediatheken, haben wir ein klares Design entwickelt: Alles Wichtige auf einen Blick, mit einer pers\u00f6nlichen Struktur, relevanten Bereichen in Ordnern und Gruppen, einem Bereich nur f\u00fcr dich und der Austausch mit anderen, dem Social Media Hub und personalisierten Newsfeeds. Alles, was dich als Nutzer interessiert, an einem Ort, ohne dass du zwischen Apps wechseln musst.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ein zus\u00e4tzliches Feature war die Idee, Favoriten in gemeinsamen Ordnern und Gruppen einfach mit anderen zu teilen. Jeder hat interessante und inspirierende Inhalte, die f\u00fcr andere relevant sein k\u00f6nnen. Nichts ist st\u00e4rker als Empfehlungen und Tipps von jemandem, der sich auskennt, sei es unter Freunden, Fremden, der Familie oder Kollegen.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Als dritte S\u00e4ule wurde die &#8222;News Cloud&#8220; hinzugef\u00fcgt, in der Nutzer Medienfeeds ausw\u00e4hlen k\u00f6nnen, sowie ein Social-Media-Hub, um alles Relevante auf einen Blick zu haben.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Im &#8222;Public&#8220;-Bereich k\u00f6nnen alle&nbsp;User Einzelposts und ganze Ordner mit allen SURFBANK-Nutzern und Informationen aus erster Hand teilen.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">SURFBANK ist die Plattform, auf der jeder Nutzer die besten Informationen, das Wissen und die neuesten Nachrichten f\u00fcr sich findet &#8211; sowohl in der Community als auch individuell.&nbsp;Jeder Nutzer kann seine Informations-, Wissens- und Nachrichtenwelt nach seinen eigenen Vorlieben gestalten und erg\u00e4nzen, unabh\u00e4ngig von Format und Quelle.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Kein Content-Algorithmus, der den Inhalt steuert, keine [st\u00f6rende] Werbung, die den Geist jeder Pers\u00f6nlichkeit und sozialen Plattform verw\u00e4ssert. Selbstbestimmt, inspirierend, echt und direkt.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Benutzer k\u00f6nnen auf SURFBANK ganz einfach alle Formate speichern und teilen [Artikel, Links, Videos, Bilder, Podcasts, Dokumente, Kontakte, Musik, Nachrichten, Standorte usw.], indem sie die Speicher- oder Freigabefunktion der Plattformen [Websites, Apps und ihre Smartphones] nutzen.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">F\u00fcr mich sind es zum Beispiel Filme, Informationen \u00fcber Projekte; F\u00fcr andere kann es sich um Urlaubsplanung, das Speichern von Rezepten, Lifestyle-Websites, Einkaufsergebnisse oder einfach um erhaltene Links handeln. Es sind keine weiteren Bookmark-Tools mehr n\u00f6tig und die \u00c4ra unz\u00e4hliger Screenshots oder offenen Tabs auf Smartphones ist vorbei.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Dar\u00fcber hinaus k\u00f6nnen Benutzer ihr gesamtes Wissen und Tipps mit Freunden, Familie und Kollegen teilen und die Inhalte in freigegebenen Ordnern, Gruppen und Communities verwenden. Dadurch k\u00f6nnen ganze Content Communities und Expertennetzwerke entstehen, die jedem Einzelnen helfen, sich weiterzuentwickeln.&nbsp;<\/p>\n\n\n\n<h4 class=\"wp-block-heading\">Was ist die Vision von SURFBANK, und welche konkreten Schritte unternehmen Sie, um diese Vision zu verwirklichen?\u00a0<\/h4>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"alignright size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"339\" height=\"600\" src=\"https:\/\/startupvalley.news\/de\/wp-content\/uploads\/sites\/2\/2024\/04\/01_SURFBANK_Home.jpg\" alt=\"\" class=\"wp-image-104872\" srcset=\"https:\/\/startupvalley.news\/de\/wp-content\/uploads\/sites\/2\/2024\/04\/01_SURFBANK_Home.jpg 339w, https:\/\/startupvalley.news\/de\/wp-content\/uploads\/sites\/2\/2024\/04\/01_SURFBANK_Home-170x300.jpg 170w, https:\/\/startupvalley.news\/de\/wp-content\/uploads\/sites\/2\/2024\/04\/01_SURFBANK_Home-237x420.jpg 237w, https:\/\/startupvalley.news\/de\/wp-content\/uploads\/sites\/2\/2024\/04\/01_SURFBANK_Home-150x265.jpg 150w, https:\/\/startupvalley.news\/de\/wp-content\/uploads\/sites\/2\/2024\/04\/01_SURFBANK_Home-300x531.jpg 300w\" sizes=\"auto, (max-width: 339px) 100vw, 339px\" \/><\/figure>\n<\/div>\n\n\n<p class=\"wp-block-paragraph\"><strong>Benjamin Syring:&nbsp;<\/strong>&nbsp;Unsere Vision ist sehr klar und einfach: wir m\u00f6chten die digitalen Erlebnisse, den Umgang mit unseren Informationen und den Nutzen, neu definieren. &nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Der Kern von SURFBANK besteht neben der pers\u00f6nlichen Medienbibliothek darin, Benutzer und Gleichgesinnte durch Empfehlungen und Tipps zusammenzubringen. Jeder Mensch ist ein Experte, ein Influencer in seiner Welt, mit gro\u00dfartigen Empfehlungen, und das Teilen und Empfangen dieser Empfehlungen schafft einen echten Benefit.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Wir verbinden die Funktionen unserer (1) <strong>pers\u00f6nlichen Social &amp; Media Content Library<\/strong>, mit (2) der <strong>Power des WOM<\/strong> und profitieren von authentischen Empfehlungen und Wissensbeitr\u00e4gen von anderen Usern auf globaler Ebene, sowie (3) der <strong>Power von Crowd-Wissen<\/strong>, also das kollektive Wissen und die Erfahrungen einer vielf\u00e4ltigen Gruppe von Einzelpersonen. Crowd-Wissen bereichert diesen Prozess, indem es eine breitere Perspektive und eine F\u00fclle unterschiedlicher Erkenntnisse bietet und es SURFBANK-Benutzern erm\u00f6glicht, fundierte Entscheidungen auf der Grundlage der kollektiven Weisheit der Crowd zu treffen.&nbsp;<\/p>\n\n\n\n<h4 class=\"wp-block-heading\">SURFBANK scheint eine breite Palette von Funktionen anzubieten. Wer ist Ihre Hauptzielgruppe, und wie erf\u00fcllen Sie spezifisch deren Bed\u00fcrfnisse?&nbsp;<\/h4>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Benjamin Syring:&nbsp;<\/strong>&nbsp;Wir sprechen grunds\u00e4tzlich alle Internet-User an. Statistisch betrachtet, ist jeder ungef\u00e4hr 7 Stunden t\u00e4glich im Netz, beruflich und privat. Man informiert sich, sucht gezielt oder surft durchs Web und Apps, nutzt Messenger-Dienste mit Freunden, Familie und Kollegen.&nbsp;&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Informationen wie Bilder, Posts, Mitteilungen, Links von Freunden, die wir behalten wollen, werden aktuell \u00fcber alle m\u00f6glichen \u201eHacks\u201c abgelegt und gespeichert, aber dadurch auch \u00fcberall verteilt. Daher sprechen wir in allererster Linie all diejenigen an, die einen zentralen Platz f\u00fcr ihre Inhalte suchen. Des Weiteren, die User, die sich mit anderen gerne austauschen, die Anregungen, Tipps und Empfehlungen von anderen, von Influencern oder Experten suchen. Selbst der berufliche Einsatz wird bedient, weil man relevante Infos zu seinem Arbeitsgebiet, Recherchen, Projekte allein oder in der Gruppe nutzen kann.&nbsp;<\/p>\n\n\n\n<h4 class=\"wp-block-heading\">Jedes Startup trifft auf Herausforderungen. Welche sind die gr\u00f6\u00dften, mit denen SURFBANK konfrontiert wird, und wie gehen Sie damit um?&nbsp;<\/h4>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Benjamin Syring:&nbsp;<\/strong>&nbsp;Die gr\u00f6\u00dfte Herausforderung ist die Priorisierung der Weiterentwicklungsm\u00f6glichkeiten und die Funktionen. Wir haben viele interessante Ideen, die wir gerne umsetzen m\u00f6chten. Wichtig ist aber, dass wir dies mit den Usern tun, was bedeutet, dass wir zuk\u00fcnftig mit der Community Bedarfe eruieren und priorisieren. Es geht darum, Funktionen zu sch\u00e4rfen und SURFBANK immer intuitiver zu machen.&nbsp;Um unsere Ideen und Pl\u00e4ne umzusetzen, setzen wir den n\u00e4chsten Schritt und sind derzeit auf der Suche nach strategischen Partnern, Investoren und Mitarbeitern. Wir suchen Fachleute mit Erfahrung in den Bereichen Medien und Social Media, die aber auch einen innovativen Ansatz f\u00fcr moderne Funktionen und Technologien sowie f\u00fcr die zuk\u00fcnftige Entwicklung mitbringen.&nbsp;<\/p>\n\n\n\n<h4 class=\"wp-block-heading\">Sie haben SURFBANK als frei von Content-Algorithmen und Werbung beschrieben. Was macht Ihre Plattform sonst noch einzigartig gegen\u00fcber anderen Angeboten auf dem Markt?&nbsp;<\/h4>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Benjamin Syring:&nbsp;<\/strong>&nbsp;Unsere Plattform ist einzigartig und trifft durch verschiedene Funktionen auf Anhieb auf einen gro\u00dfen Bedarf, f\u00fcr den es zwar bereits vereinzelte M\u00f6glichkeiten gibt, aber keine ma\u00dfgeschneiderte All-in-One L\u00f6sung.&nbsp;&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Wir treffen auf einen Nerv der Zeit: es gibt eine F\u00fclle an Informationen, Angeboten, Apps, alles ist irgendwo. Wir b\u00fcndeln die relevanten Funktionen und M\u00f6glichkeiten und verbinden diese mit technischen M\u00f6glichkeiten (AI), aber auch mit dem gesellschaftlichen Bedarf, weil Informationen und Wissen in Verbindung mit den eigenen Interessen zuk\u00fcnftig noch mehr Bedeutung haben werden.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Mit unserer Plattform ist jeder User selbstbestimmt und bleibt es. Wir sind nicht davon angetrieben, anderen Content oder Werbung anzubieten, sondern davon, jedem zu erm\u00f6glichen, den besten f\u00fcr sich zu nutzen.&nbsp;&nbsp;<\/p>\n\n\n\n<h4 class=\"wp-block-heading\">Wie plant SURFBANK, sich in den n\u00e4chsten Jahren weiterzuentwickeln? Gibt es bestimmte Meilensteine oder neue Funktionen, die Sie einf\u00fchren m\u00f6chten?&nbsp;<\/h4>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Benjamin Syring:&nbsp;<\/strong>&nbsp;Wir haben eine klare Strategie, wie wir das Produkt weiterentwickeln m\u00f6chten, ma\u00dfgeschneidert auf die Bedarfe unserer User. Dabei wollen wir auf regionale und kulturelle Aspekte eingehen. Wir wollen User weltweit verbinden und ein Hub anbieten, in dem jeder von den Erfahrungen und dem Wissen anderer teilhaben kann. Jeder hat Interessen und kennt sich zu einem Thema aus, hat dazu Content gesammelt. Genau das mag f\u00fcr andere relevant, inspirierend und interessant sein.&nbsp;&nbsp;<\/p>\n\n\n\n<h4 class=\"wp-block-heading\">In welcher Weise nutzt SURFBANK Feedback und Interaktionen innerhalb der Community, um die Plattform weiterzuentwickeln und anzupassen?&nbsp;&nbsp;<\/h4>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Benjamin Syring:&nbsp;<\/strong>&nbsp;Eines der angesprochenen Funktionen wird eine Art integrierter Community-Center sein, in dem unsere User ihre Anregungen, Ideen und Kritik \u00e4u\u00dfern k\u00f6nnen. Wir sehen dies als einen relevanten Erfolgsfaktor der Plattform an, weil der User immer am besten wei\u00df, was er braucht und wie er das Tool am besten Nutzen kann. Zudem kommen die besten Ideen immer aus einer Crowd.&nbsp;&nbsp;<\/p>\n\n\n\n<h4 class=\"wp-block-heading\">Datenschutz ist ein gro\u00dfes Thema bei digitalen Plattformen. Wie gew\u00e4hrleistet SURFBANK, dass die pers\u00f6nlichen Informationen der Nutzer gesch\u00fctzt sind?&nbsp;<\/h4>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Benjamin Syring:&nbsp;<\/strong>&nbsp;Wir haben bereits w\u00e4hrend der Entwicklung des Konzeptes und der Plattform einen externen Datenschutzbeauftragten eingebunden, da uns das Thema wichtig und ist wir es sehr ernst nehmen. Ohne hohe Sicherheitsstandards und strenge Compliance-Richtlinien darf man heute ein solches Projekt nicht starten, aus Verantwortung gegen\u00fcber den Usern und deren Vertrauen.&nbsp;&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Die Daten sind auf einem gesch\u00fctzten europ\u00e4ischen Server sicher und wir f\u00fchren regelm\u00e4\u00dfige Tests durch. Dar\u00fcber hinaus haben wir eine eigene Policy definiert, die den Austausch und die Inhalte auf der Plattform regelt.&nbsp;<\/p>\n\n\n\n<h4 class=\"wp-block-heading\">Wie finanziert sich SURFBANK, insbesondere wenn Sie keine Werbung schalten und keinen Content-Algorithmus verwenden?&nbsp;<\/h4>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Benjamin Syring:&nbsp;<\/strong>&nbsp;Wir haben uns bisher aus Eigenmitteln finanziert. Um unsere ambitionierten Ziele und Funktionen umsetzen zu k\u00f6nnen, sind wir aktuell mit interessanten Partnern in Gespr\u00e4chen, um strategische Allianzen aber auch Investoren mit einbinden zu k\u00f6nnen.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Die App soll weiterhin kosten- und werbefrei bleiben. F\u00fcr eine Signature-Premiumfunktion werden wir einige neue und \u00fcberraschende Funktionen entwickeln. Wir sind \u00fcberzeugt, dass die meisten User gerne mit einem \u00fcberschaubaren Monatsbeitrag zur Finanzierung beitragen.&nbsp;<\/p>\n\n\n\n<h4 class=\"wp-block-heading\">Welchen Einfluss hatte die Gr\u00fcndungsumgebung und der Standort auf die Entwicklung von SURFBANK?\u00a0<\/h4>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"alignleft size-full is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"600\" src=\"https:\/\/startupvalley.news\/de\/wp-content\/uploads\/sites\/2\/2024\/04\/SURFBANK_Management_Team.jpg\" alt=\"\" class=\"wp-image-104873\" style=\"width:399px;height:auto\" srcset=\"https:\/\/startupvalley.news\/de\/wp-content\/uploads\/sites\/2\/2024\/04\/SURFBANK_Management_Team.jpg 600w, https:\/\/startupvalley.news\/de\/wp-content\/uploads\/sites\/2\/2024\/04\/SURFBANK_Management_Team-300x300.jpg 300w, https:\/\/startupvalley.news\/de\/wp-content\/uploads\/sites\/2\/2024\/04\/SURFBANK_Management_Team-150x150.jpg 150w, https:\/\/startupvalley.news\/de\/wp-content\/uploads\/sites\/2\/2024\/04\/SURFBANK_Management_Team-420x420.jpg 420w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/><figcaption class=\"wp-element-caption\">SURFBANK, Benjamin Syring, Ingo Fr\u00f6hlich, Oliver Rudolph, Management Team<\/figcaption><\/figure>\n<\/div>\n\n\n<p class=\"wp-block-paragraph\"><strong>Benjamin Syring:&nbsp;<\/strong>&nbsp;Mein aktueller Standort ist Baden-W\u00fcrttemberg, konkret Stuttgart, wo es bereits eine interessante Startup- und Business Szene gibt. F\u00fcr den Aufbau und die Entwicklung ist es optimal. Die zweite Dimension ist die digitale Zusammenarbeit und entsprechende Tools, die es uns erlauben, als internationales und erfahrenes Team trotzdem eng vernetzt zu sein und effizient zu arbeiten. Es gibt innovative Projektmanagement- und Kommunikationsplattformen, die wir nutzen, um immer up-to-date zu sein. Hinzu kommt, dass wir als Team breit aufgestellt und erfahren sind, sehr engagiert und initiativ und dabei fokussiert unseren Weg gehen.&nbsp;<\/p>\n\n\n\n<h4 class=\"wp-block-heading\">K\u00f6nnten Sie drei Ratschl\u00e4ge nennen, die Sie anderen Gr\u00fcndern geben w\u00fcrden, die ein \u00e4hnlich ambitioniertes Projekt starten m\u00f6chten?&nbsp;<\/h4>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Benjamin Syring:&nbsp;<\/strong>&nbsp;Sehr gerne: Alles beginnt mit der Beschreibung der Idee, dem Konzept mit einer klaren Zielbeschreibung, das von einem starken Umsetzungswillen getragen wird. Dazu geh\u00f6rt die Beschreibung des Teams und der ben\u00f6tigten Funktionen sowie ein Businessplan, der den finanziellen Erfolg rational aufzeigt. Unter anderem auf der Website &#8222;Gr\u00fcnderplattform&#8220; findet ihr alle ben\u00f6tigten Ressourcen. Sucht euch unbedingt Menschen aus eurem Umfeld, die euch bei der Umsetzung unterst\u00fctzen k\u00f6nnen.&nbsp;<\/p>\n\n\n\n<h4 class=\"wp-block-heading\">Wie misst SURFBANK den Erfolg ihrer Plattform, und welche Kriterien oder Metriken sind Ihnen dabei am wichtigsten?&nbsp;<\/h4>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Benjamin Syring:\u00a0<\/strong>\u00a0Wir haben parallel eine eigene Analytics-Plattform entwickelt, die uns s\u00e4mtliche Daten und Statistiken zu User-Zahlen und der User-Journey aufzeigt. Wir verfolgen genau, wie die Plattform genutzt wird. Dar\u00fcber hinaus zeigen uns die digitalen Auswertungen unserer Kommunikation, wie die Views, Konversion, das like-feedback und die Kommentare dazu sind sowie das Medienfeedback unserer Media Releases. Dar\u00fcber hinaus sehen wir es erfreulicherweise sehr deutlich an den Anfragen von potenziellen Partnern, Investoren aber auch Personen, die f\u00fcr die Firma und das Produkt gerne arbeiten m\u00f6chten.\u00a0<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Wir bedanken uns bei\u00a0<a href=\"https:\/\/www.linkedin.com\/in\/benjamin-syring-002aa141\/\" target=\"_blank\" rel=\"noreferrer noopener\">Benjamin Syring<\/a>\u00a0f\u00fcr das Interview<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Aussagen des Autors und des Interviewpartners geben nicht unbedingt die Meinung der Redaktion und des Verlags wieder<\/p>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\" style=\"max-width:800px\"\/>\n\n\n\n<h2 class=\"wp-block-heading\">Premium Start-up: SURFBANK<\/h2>\n\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-8f761849 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:33.33%\">\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"1000\" height=\"1000\" src=\"https:\/\/startupvalley.news\/de\/wp-content\/uploads\/sites\/2\/2024\/04\/SURFBANK.png\" alt=\"\" class=\"wp-image-104869\" srcset=\"https:\/\/startupvalley.news\/de\/wp-content\/uploads\/sites\/2\/2024\/04\/SURFBANK.png 1000w, https:\/\/startupvalley.news\/de\/wp-content\/uploads\/sites\/2\/2024\/04\/SURFBANK-300x300.png 300w, https:\/\/startupvalley.news\/de\/wp-content\/uploads\/sites\/2\/2024\/04\/SURFBANK-150x150.png 150w, https:\/\/startupvalley.news\/de\/wp-content\/uploads\/sites\/2\/2024\/04\/SURFBANK-768x768.png 768w, https:\/\/startupvalley.news\/de\/wp-content\/uploads\/sites\/2\/2024\/04\/SURFBANK-420x420.png 420w, https:\/\/startupvalley.news\/de\/wp-content\/uploads\/sites\/2\/2024\/04\/SURFBANK-696x696.png 696w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/><\/figure>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:66.66%\">\n<h3 class=\"wp-block-heading\">Kontakt:<\/h3>\n\n\n<p><strong>CEO SRFBNK GmbH | SURFBANK Web\/ App<\/strong><br \/>\nOelschl\u00e4gerstrasse 30<br \/>\nD-70619 Stuttgart<\/p>\n<p><a href=\"https:\/\/www.surfbank.org\" target=\"_blank\" rel=\"noopener\">https:\/\/www.surfbank.org<\/a><\/p>\n<p><strong>Ansprechpartner<\/strong>: Benjamin Syring<\/p>\n<p><strong>Social Media:<\/strong><br \/>\n<a href=\"https:\/\/www.linkedin.com\/company\/surfbank\/\" target=\"_blank\" rel=\"noopener\">LinkedIn <\/a><br \/>\n<a href=\"https:\/\/www.instagram.com\/srfbnk\/\" target=\"_blank\" rel=\"noopener\">Instagram<\/a><br \/>\n<a href=\"https:\/\/www.facebook.com\/profile.php?id=61551460583743\" target=\"_blank\" rel=\"noopener\">Facebook<\/a><br \/>\n<a href=\"https:\/\/www.youtube.com\/@SURFBANK-wq4ri\" target=\"_blank\" rel=\"noopener\">YouTube<\/a><br \/>\n<a href=\"https:\/\/surfbank.org\/auth\/sign-in?callbackUrl=https%3A%2F%2Fsurfbank.org%2F\" target=\"_blank\" rel=\"noopener\">Apps<\/a><\/p>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>SURFBANK ist ein innovatives Unternehmen, das eine Plattform entwickelt hat, um pers\u00f6nliche Inhalte wie Artikel, Links und Medien in einer zentralisierten Medienbibliothek zu organisieren und zu teilen, wodurch Nutzer einfach auf relevante Informationen zugreifen und diese mit anderen austauschen k\u00f6nnen<\/p>\n","protected":false},"author":4,"featured_media":104871,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[26473,15009],"tags":[93,3070,4180,10395,126,200,491,23306],"class_list":["post-104868","post","type-post","status-publish","format-standard","has-post-thumbnail","category-interviews","category-premium-startups","tag-community","tag-content","tag-datenschutz","tag-empfehlungen","tag-innovation","tag-plattform","tag-social-media","tag-user"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.3 (Yoast SEO v28.3) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>SURFBANK: Aufbau einer digitalen Customer Experience<\/title>\n<meta name=\"description\" content=\"SURFBANK ist ein innovatives Unternehmen mit einer Plattform, die pers\u00f6nliche Inhalte zentral organisiert und teilt\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/startupvalley.news\/de\/surfbank\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Verwalten Sie Ihre digitalen Inhalte m\u00fchelos\" \/>\n<meta property=\"og:description\" content=\"SURFBANK ist ein innovatives Unternehmen mit einer Plattform, die pers\u00f6nliche Inhalte zentral organisiert und teilt\" \/>\n<meta property=\"og:url\" content=\"https:\/\/startupvalley.news\/de\/surfbank\/\" \/>\n<meta property=\"og:site_name\" content=\"StartupValley\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/startupvalleynews\" \/>\n<meta property=\"article:published_time\" content=\"2024-04-24T08:38:25+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-06-11T06:27:43+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/startupvalley.news\/de\/wp-content\/uploads\/sites\/2\/2024\/04\/SURFBANK-Benjamin-Syring.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"784\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Sabine Els\u00e4sser\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@startup_valley\" \/>\n<meta name=\"twitter:site\" content=\"@startup_valley\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Sabine Els\u00e4sser\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"12\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\\\/\\\/startupvalley.news\\\/de\\\/surfbank\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/startupvalley.news\\\/de\\\/surfbank\\\/\"},\"author\":{\"name\":\"Sabine Els\u00e4sser\",\"@id\":\"https:\\\/\\\/startupvalley.news\\\/de\\\/#\\\/schema\\\/person\\\/959af3b7c76b6212078460c1b7840814\"},\"headline\":\"Verwalten Sie Ihre digitalen Inhalte m\u00fchelos\",\"datePublished\":\"2024-04-24T08:38:25+00:00\",\"dateModified\":\"2026-06-11T06:27:43+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/startupvalley.news\\\/de\\\/surfbank\\\/\"},\"wordCount\":2188,\"publisher\":{\"@id\":\"https:\\\/\\\/startupvalley.news\\\/de\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/startupvalley.news\\\/de\\\/surfbank\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/startupvalley.news\\\/de\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2024\\\/04\\\/SURFBANK-Benjamin-Syring.jpg\",\"keywords\":[\"Community\",\"Content\",\"Datenschutz\",\"Empfehlungen\",\"Innovation\",\"Plattform\",\"social media\",\"User\"],\"articleSection\":[\"Interviews\",\"Premium Startups\"],\"inLanguage\":\"de\",\"copyrightYear\":\"2024\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/startupvalley.news\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/startupvalley.news\\\/de\\\/surfbank\\\/\",\"url\":\"https:\\\/\\\/startupvalley.news\\\/de\\\/surfbank\\\/\",\"name\":\"SURFBANK: Aufbau einer digitalen Customer Experience\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/startupvalley.news\\\/de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/startupvalley.news\\\/de\\\/surfbank\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/startupvalley.news\\\/de\\\/surfbank\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/startupvalley.news\\\/de\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2024\\\/04\\\/SURFBANK-Benjamin-Syring.jpg\",\"datePublished\":\"2024-04-24T08:38:25+00:00\",\"dateModified\":\"2026-06-11T06:27:43+00:00\",\"description\":\"SURFBANK ist ein innovatives Unternehmen mit einer Plattform, die pers\u00f6nliche Inhalte zentral organisiert und teilt\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/startupvalley.news\\\/de\\\/surfbank\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/startupvalley.news\\\/de\\\/surfbank\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/startupvalley.news\\\/de\\\/surfbank\\\/#primaryimage\",\"url\":\"https:\\\/\\\/startupvalley.news\\\/de\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2024\\\/04\\\/SURFBANK-Benjamin-Syring.jpg\",\"contentUrl\":\"https:\\\/\\\/startupvalley.news\\\/de\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2024\\\/04\\\/SURFBANK-Benjamin-Syring.jpg\",\"width\":1200,\"height\":784,\"caption\":\"surfbank\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/startupvalley.news\\\/de\\\/surfbank\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/startupvalley.news\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Verwalten Sie Ihre digitalen Inhalte m\u00fchelos\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/startupvalley.news\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/startupvalley.news\\\/de\\\/\",\"name\":\"StartupValley\",\"description\":\"Startup-News, Funding &amp; Gr\u00fcnder-Interviews\",\"publisher\":{\"@id\":\"https:\\\/\\\/startupvalley.news\\\/de\\\/#organization\"},\"alternateName\":\"StartupValley Magazin\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/startupvalley.news\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/startupvalley.news\\\/de\\\/#organization\",\"name\":\"StartupValley Media\",\"url\":\"https:\\\/\\\/startupvalley.news\\\/de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/startupvalley.news\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/startupvalley.news\\\/de\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2020\\\/12\\\/StartupValley-LOGO-neu-retina.png\",\"contentUrl\":\"https:\\\/\\\/startupvalley.news\\\/de\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2020\\\/12\\\/StartupValley-LOGO-neu-retina.png\",\"width\":460,\"height\":180,\"caption\":\"StartupValley Media\"},\"image\":{\"@id\":\"https:\\\/\\\/startupvalley.news\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/startupvalleynews\",\"https:\\\/\\\/x.com\\\/startup_valley\",\"https:\\\/\\\/www.twitch.tv\\\/startupvalley\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/startupvalleymagazine\",\"https:\\\/\\\/www.instagram.com\\\/startup_valley\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/startupvalley.news\\\/de\\\/#\\\/schema\\\/person\\\/959af3b7c76b6212078460c1b7840814\",\"name\":\"Sabine Els\u00e4sser\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/eb042e409bc170310e48b4956c0f57baf35eae7a9a109f7fefcaccc946b3d77c?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/eb042e409bc170310e48b4956c0f57baf35eae7a9a109f7fefcaccc946b3d77c?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/eb042e409bc170310e48b4956c0f57baf35eae7a9a109f7fefcaccc946b3d77c?s=96&d=mm&r=g\",\"caption\":\"Sabine Els\u00e4sser\"},\"description\":\"Sabine Elsaesser is an experienced entrepreneur and media\\\/startup expert. Since 2016, she has served as the Chief Editor and CEO of StartupValley Media &amp; Publishing. In this role, she is responsible for managing the company and providing strategic direction for its media and publishing activities. Sabine Elsaesser takes great pleasure in assisting individuals and businesses in reaching their full potential. Her expertise in establishing sales organizations and her passion for innovation make her a valuable advocate for startups and entrepreneurs.\",\"sameAs\":[\"https:\\\/\\\/www.instagram.com\\\/sabineelsaesser\",\"https:\\\/\\\/www.linkedin.com\\\/in\\\/sabine-elsaesser\"],\"url\":\"https:\\\/\\\/startupvalley.news\\\/de\\\/author\\\/sabineelsaesser\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"SURFBANK: Aufbau einer digitalen Customer Experience","description":"SURFBANK ist ein innovatives Unternehmen mit einer Plattform, die pers\u00f6nliche Inhalte zentral organisiert und teilt","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/startupvalley.news\/de\/surfbank\/","og_locale":"de_DE","og_type":"article","og_title":"Verwalten Sie Ihre digitalen Inhalte m\u00fchelos","og_description":"SURFBANK ist ein innovatives Unternehmen mit einer Plattform, die pers\u00f6nliche Inhalte zentral organisiert und teilt","og_url":"https:\/\/startupvalley.news\/de\/surfbank\/","og_site_name":"StartupValley","article_publisher":"https:\/\/www.facebook.com\/startupvalleynews","article_published_time":"2024-04-24T08:38:25+00:00","article_modified_time":"2026-06-11T06:27:43+00:00","og_image":[{"width":1200,"height":784,"url":"https:\/\/startupvalley.news\/de\/wp-content\/uploads\/sites\/2\/2024\/04\/SURFBANK-Benjamin-Syring.jpg","type":"image\/jpeg"}],"author":"Sabine Els\u00e4sser","twitter_card":"summary_large_image","twitter_creator":"@startup_valley","twitter_site":"@startup_valley","twitter_misc":{"Verfasst von":"Sabine Els\u00e4sser","Gesch\u00e4tzte Lesezeit":"12\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/startupvalley.news\/de\/surfbank\/#article","isPartOf":{"@id":"https:\/\/startupvalley.news\/de\/surfbank\/"},"author":{"name":"Sabine Els\u00e4sser","@id":"https:\/\/startupvalley.news\/de\/#\/schema\/person\/959af3b7c76b6212078460c1b7840814"},"headline":"Verwalten Sie Ihre digitalen Inhalte m\u00fchelos","datePublished":"2024-04-24T08:38:25+00:00","dateModified":"2026-06-11T06:27:43+00:00","mainEntityOfPage":{"@id":"https:\/\/startupvalley.news\/de\/surfbank\/"},"wordCount":2188,"publisher":{"@id":"https:\/\/startupvalley.news\/de\/#organization"},"image":{"@id":"https:\/\/startupvalley.news\/de\/surfbank\/#primaryimage"},"thumbnailUrl":"https:\/\/startupvalley.news\/de\/wp-content\/uploads\/sites\/2\/2024\/04\/SURFBANK-Benjamin-Syring.jpg","keywords":["Community","Content","Datenschutz","Empfehlungen","Innovation","Plattform","social media","User"],"articleSection":["Interviews","Premium Startups"],"inLanguage":"de","copyrightYear":"2024","copyrightHolder":{"@id":"https:\/\/startupvalley.news\/#organization"}},{"@type":"WebPage","@id":"https:\/\/startupvalley.news\/de\/surfbank\/","url":"https:\/\/startupvalley.news\/de\/surfbank\/","name":"SURFBANK: Aufbau einer digitalen Customer Experience","isPartOf":{"@id":"https:\/\/startupvalley.news\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/startupvalley.news\/de\/surfbank\/#primaryimage"},"image":{"@id":"https:\/\/startupvalley.news\/de\/surfbank\/#primaryimage"},"thumbnailUrl":"https:\/\/startupvalley.news\/de\/wp-content\/uploads\/sites\/2\/2024\/04\/SURFBANK-Benjamin-Syring.jpg","datePublished":"2024-04-24T08:38:25+00:00","dateModified":"2026-06-11T06:27:43+00:00","description":"SURFBANK ist ein innovatives Unternehmen mit einer Plattform, die pers\u00f6nliche Inhalte zentral organisiert und teilt","breadcrumb":{"@id":"https:\/\/startupvalley.news\/de\/surfbank\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/startupvalley.news\/de\/surfbank\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/startupvalley.news\/de\/surfbank\/#primaryimage","url":"https:\/\/startupvalley.news\/de\/wp-content\/uploads\/sites\/2\/2024\/04\/SURFBANK-Benjamin-Syring.jpg","contentUrl":"https:\/\/startupvalley.news\/de\/wp-content\/uploads\/sites\/2\/2024\/04\/SURFBANK-Benjamin-Syring.jpg","width":1200,"height":784,"caption":"surfbank"},{"@type":"BreadcrumbList","@id":"https:\/\/startupvalley.news\/de\/surfbank\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/startupvalley.news\/de\/"},{"@type":"ListItem","position":2,"name":"Verwalten Sie Ihre digitalen Inhalte m\u00fchelos"}]},{"@type":"WebSite","@id":"https:\/\/startupvalley.news\/de\/#website","url":"https:\/\/startupvalley.news\/de\/","name":"StartupValley","description":"Startup-News, Funding &amp; Gr\u00fcnder-Interviews","publisher":{"@id":"https:\/\/startupvalley.news\/de\/#organization"},"alternateName":"StartupValley Magazin","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/startupvalley.news\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/startupvalley.news\/de\/#organization","name":"StartupValley Media","url":"https:\/\/startupvalley.news\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/startupvalley.news\/de\/#\/schema\/logo\/image\/","url":"https:\/\/startupvalley.news\/de\/wp-content\/uploads\/sites\/2\/2020\/12\/StartupValley-LOGO-neu-retina.png","contentUrl":"https:\/\/startupvalley.news\/de\/wp-content\/uploads\/sites\/2\/2020\/12\/StartupValley-LOGO-neu-retina.png","width":460,"height":180,"caption":"StartupValley Media"},"image":{"@id":"https:\/\/startupvalley.news\/de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/startupvalleynews","https:\/\/x.com\/startup_valley","https:\/\/www.twitch.tv\/startupvalley","https:\/\/www.linkedin.com\/company\/startupvalleymagazine","https:\/\/www.instagram.com\/startup_valley"]},{"@type":"Person","@id":"https:\/\/startupvalley.news\/de\/#\/schema\/person\/959af3b7c76b6212078460c1b7840814","name":"Sabine Els\u00e4sser","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/eb042e409bc170310e48b4956c0f57baf35eae7a9a109f7fefcaccc946b3d77c?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/eb042e409bc170310e48b4956c0f57baf35eae7a9a109f7fefcaccc946b3d77c?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/eb042e409bc170310e48b4956c0f57baf35eae7a9a109f7fefcaccc946b3d77c?s=96&d=mm&r=g","caption":"Sabine Els\u00e4sser"},"description":"Sabine Elsaesser is an experienced entrepreneur and media\/startup expert. Since 2016, she has served as the Chief Editor and CEO of StartupValley Media &amp; Publishing. In this role, she is responsible for managing the company and providing strategic direction for its media and publishing activities. Sabine Elsaesser takes great pleasure in assisting individuals and businesses in reaching their full potential. Her expertise in establishing sales organizations and her passion for innovation make her a valuable advocate for startups and entrepreneurs.","sameAs":["https:\/\/www.instagram.com\/sabineelsaesser","https:\/\/www.linkedin.com\/in\/sabine-elsaesser"],"url":"https:\/\/startupvalley.news\/de\/author\/sabineelsaesser\/"}]}},"_links":{"self":[{"href":"https:\/\/startupvalley.news\/de\/wp-json\/wp\/v2\/posts\/104868","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/startupvalley.news\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/startupvalley.news\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/startupvalley.news\/de\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/startupvalley.news\/de\/wp-json\/wp\/v2\/comments?post=104868"}],"version-history":[{"count":2,"href":"https:\/\/startupvalley.news\/de\/wp-json\/wp\/v2\/posts\/104868\/revisions"}],"predecessor-version":[{"id":104875,"href":"https:\/\/startupvalley.news\/de\/wp-json\/wp\/v2\/posts\/104868\/revisions\/104875"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/startupvalley.news\/de\/wp-json\/wp\/v2\/media\/104871"}],"wp:attachment":[{"href":"https:\/\/startupvalley.news\/de\/wp-json\/wp\/v2\/media?parent=104868"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/startupvalley.news\/de\/wp-json\/wp\/v2\/categories?post=104868"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/startupvalley.news\/de\/wp-json\/wp\/v2\/tags?post=104868"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}