{"id":107502,"date":"2024-08-01T10:19:47","date_gmt":"2024-08-01T08:19:47","guid":{"rendered":"https:\/\/startupvalley.news\/de\/?p=107502"},"modified":"2026-06-11T08:24:48","modified_gmt":"2026-06-11T06:24:48","slug":"kunstimperium","status":"publish","type":"post","link":"https:\/\/startupvalley.news\/de\/kunstimperium\/","title":{"rendered":"K\u00f6nnte dies die perfekte L\u00f6sung f\u00fcr Lesemuffel sein?"},"content":{"rendered":"\n<h2 class=\"wp-block-heading\" id=\"h-kunstimperium-bringt-mit-innovativen-hochwertigen-buchern-und-fotocomics-neuen-schwung-in-die-welt-des-lesens-und-fordert-die-freude-an-geschichten-fur-alle-altersgruppen\">Kunstimperium bringt mit innovativen, hochwertigen B\u00fcchern und Fotocomics neuen Schwung in die Welt des Lesens und f\u00f6rdert die Freude an Geschichten f\u00fcr alle Altersgruppen<\/h2>\n\n\n\n<h4 class=\"wp-block-heading\" id=\"h-konnten-sie-ihr-startup-und-die-grunder-hinter-dem-unternehmen-vorstellen\">K\u00f6nnten Sie Ihr Startup und die Gr\u00fcnder hinter dem Unternehmen vorstellen?<\/h4>\n\n\n\n<p class=\"wp-block-paragraph\">Kunstimperium wurde von meiner Mutter Tanja und mir, ihrer Tochter Vanessa Blo\u00df gegr\u00fcndet. Im Rahmen von Kunstimperium lassen wir unserer Kreativit\u00e4t freien Lauf, um den Menschen Neues und Besonderes zu bieten. Dies geschieht in erster Linie meist in Form von neuartigen, hochwertigen B\u00fcchern.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Darunter befinden sich das erste echte Blinddatebook, das erste alltagstaugliche Kr\u00e4uterbuch als schnelles Nachschlagewerk, die ersten Fotocomics f\u00fcr Kinder und Erwachsene und das erste liebevollgestaltete Buchjournal. Dar\u00fcber hinaus haben wir die ersten Vorlesevideos entwickelt und autorengelesene H\u00f6rb\u00fccher. Einige weitere Projekte unter anderem im Bereich Spielwaren befinden sich gerade ebenfalls in der Entwicklung.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Bei all unseren Produkten ist es uns wichtig, dass sie nicht nur etwas Besonderes sind, sondern auch eine entsprechend gute Qualit\u00e4t haben, dementsprechend suchen wir auch unsere Kooperationspartner aus. Au\u00dferdem setzen m\u00f6chten wir eine gewisse Wertsch\u00e4tzung gew\u00e4hrleisten, daher sind unsere Produkte nicht im breiten Handel, sondern nur exklusiv in unserem Shop und zu bestimmten Kooperationsaktionen als Bundle \u00fcber unsere jeweiligen Kooperationspartner erh\u00e4ltlich.<\/p>\n\n\n\n<h4 class=\"wp-block-heading\" id=\"h-welche-vision-verfolgen-sie-mit-ihrem-unternehmen-und-wie-wollen-sie-diese-vision-erreichen\">Welche Vision verfolgen Sie mit Ihrem Unternehmen und wie wollen Sie diese Vision erreichen?<\/h4>\n\n\n\n<p class=\"wp-block-paragraph\">Mit unseren Fotocomics m\u00f6chten wir mehr Menschen zum Lesen motivieren, vor allem Kinder und M\u00e4nner. Dies erreichen wir mit verschiedenen innovativen Marktneuheiten, wie beispielsweise Fotocomics aber auch indem wir unsere Romane und Geschichten mit kleinen passenden Illustrationen am Textrand versehen.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Beides f\u00fchrt dazu, dass die Geschichten einfacher gelesen werden k\u00f6nnen, die Leser mehr Spa\u00df beim Lesen empfinden und das Vorstellungsverm\u00f6gen unterst\u00fctzt wird.<br>All diese Vorteile sorgen daf\u00fcr, dass sowohl Menschen, die Schwierigkeiten mit dem Vorstellungsverm\u00f6gen haben, als auch Menschen, die aufgrund der schlichten und geballten schwarz- wei\u00df Texte nicht lesen, Interesse und Spa\u00df am Lesen entdecken.<\/p>\n\n\n\n<h4 class=\"wp-block-heading\" id=\"h-wer-ist-ihre-hauptzielgruppe-und-wie-stellen-sie-sicher-dass-sie-deren-bedurfnisse-erfullen\">Wer ist Ihre Hauptzielgruppe und wie stellen Sie sicher, dass Sie deren Bed\u00fcrfnisse erf\u00fcllen?<\/h4>\n\n\n\n<p class=\"wp-block-paragraph\">Unsere Zielgruppe sind sowohl Kinder ab 1,5 Jahren als auch Erwachsene Leser und solche, die es werden wollen. Mit unseren Fotocomics f\u00fcr Kinder und Erwachsene schaffen wir es, die \u00fcbliche Einstiegsbarriere in die Geschichte abzubauen und deren Vorstellungsverm\u00f6gen zu unterst\u00fctzen. Normalerweise m\u00fcssen zun\u00e4chst Illustrationen und\/ oder einfache Schwarz- wei\u00df-Texte- die vorher auch noch gelesen werden m\u00fcssen- in unsere Realit\u00e4t \u00fcbersetzt werden. Dies setzt ein gewisses Ma\u00df an Disziplin, Vorstellungsverm\u00f6gen und unter Umst\u00e4nden auch Lesekenntnisse voraus. Da dies alles bei unseren Fotocomics entf\u00e4llt erh\u00f6ht sich der Lesespa\u00df deutlich und vereinfacht das Lesen der Geschichte.<\/p>\n\n\n\n<h4 class=\"wp-block-heading\" id=\"h-was-waren-die-grossten-herausforderungen-denen-sie-bisher-begegnet-sind-und-wie-haben-sie-diese-bewaltigt\">Was waren die gr\u00f6\u00dften Herausforderungen, denen Sie bisher begegnet sind, und wie haben Sie diese bew\u00e4ltigt?<\/h4>\n\n\n\n<p class=\"wp-block-paragraph\">Wie in jedem Unternehmen gibt es immer wieder verschiedene, oft auch situationsbedingte Herausforderungen. Einige davon erledigen sich schneller und andere bed\u00fcrfen gr\u00f6\u00dferer und l\u00e4ngerer Anstrengungen. Doch letztlich kommt es in meinen Augen immer darauf an eine L\u00f6sung zu finden und einfach anzupacken. Dadurch hat man die M\u00f6glichkeit mit jeder Herausforderung zu lernen und zu wachsen.<\/p>\n\n\n\n<h5 class=\"wp-block-heading\" id=\"h-eine-anfanglich-grosse-herausforderung-waren-die-fehlenden-kenntnisse-im-bereich-der-adobe-programme-sowie-design-layout-und-gestaltung-da-eine-ausbildung-im-bereich-mediengestaltung-leider-keine-abhilfe-schuf-und-sich-auch-keine-verlassliche-hilfe-fand-bleib-also-nur-der-klassische-learning-by-doing-weg-ubrig\">Eine anf\u00e4nglich gro\u00dfe Herausforderung waren die fehlenden Kenntnisse im Bereich der Adobe- Programme, sowie Design, Layout und Gestaltung. Da eine Ausbildung im Bereich Mediengestaltung leider keine Abhilfe schuf und sich auch keine verl\u00e4ssliche Hilfe fand, bleib also nur der klassische \u201eLearning by doing\u201c- Weg \u00fcbrig.<\/h5>\n\n\n\n<p class=\"wp-block-paragraph\">Doch wie bereits erw\u00e4hnt w\u00e4chst man durch seine Herausforderungen \u00fcber sich hinaus und diese anfangs, zugegeben verhasste, Herausforderung stellt sich bis heute als gr\u00f6\u00dftes Geschenk heraus. Denn dank dieser Entwicklung, dass ich mir die Gestaltung unserer B\u00fccher mittels der Adobe Programme selbstbeibringen und die B\u00fccher allein gestalten musste, entstanden \u00fcberhaupt erst all unsere Innovationen (abgesehen von den Fotocomics) und entwickeln sich bis heute viele weitere, oft auch spontane Innovationen.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Eine weitere Herausforderung, die wir uns selbst gestellt hatten, war die Leipziger Buchmesse im M\u00e4rz 2024. Diese brachte mehrere Herausforderungen mit sich. Allein schon die Tatsache, dass wir die Messe vorher nie besucht hatten und uns daher s\u00e4mtliche Kenntnisse fehlten, machte es ausgesprochen spannend. Aber auch unter anderem der Zeitdruck und die hohe Messlatte, die ich mir selbst immer wieder lege. Oder die spontane Organisation eines LWKs war eine Herausforderung, die sich aufgrund der abweichenden Lieferart und des Lieferumfangs etwas anders gestaltete als besprochen. <\/p>\n\n\n\n<h5 class=\"wp-block-heading\" id=\"h-hierfur-galt-wie-bei-allen-anderen-herausforderungen-auch\">Hierf\u00fcr galt, wie bei allen anderen Herausforderungen auch: <\/h5>\n\n\n\n<p class=\"wp-block-paragraph\">L\u00f6sung finden und loslegen. In diesem Fall hie\u00df das also zwei Tage telefonieren und den letzten LKW, der im Umkreis von 90km zum ben\u00f6tigten Zeitraum noch verf\u00fcgbar war, finden und buchen. Wie es allerdings bei vielen Herausforderungen so ist, ziehen sie nach der Hauptherausforderung noch ein paar kleinere Nebenherausforderungen hinter sich her. So war der LKW zum Gl\u00fcck da, allerdings kam dann der Gedanke, wo wir diesen Parken w\u00fcrden bzw. ob an der Ferienwohnung genug Platz w\u00e4re. Doch dies war zum Gl\u00fcck \u00fcberhaupt kein Problem. Die letzte Schwierigkeit war dann noch einen Hubwagen im Umkreis ausleihen zu k\u00f6nnen, aber gl\u00fccklicherweise lie\u00df sich auch hierf\u00fcr eine passende L\u00f6sung finden.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Genauso verhielt es sich w\u00e4hrend des Messebetriebs als sich nach dem ersten Tag bemerkbar machte, dass sich viele Besucher nicht an die B\u00fccher herantrauten, da unser Stand zu liebevoll dekoriert war. Ein weiterer Teil der Besucher wusste nicht so recht, was f\u00fcr B\u00fccher wir hier anboten. Also setzte ich mich nach Messeschluss um 22Uhr an den Laptop und gestaltete Plakate und Popup- F\u00e4hnchen f\u00fcr den Stand. Meine Eltern zogen am n\u00e4chsten Morgen, vor Messeer\u00f6ffnung los und druckten diese aus. <\/p>\n\n\n\n<h5 class=\"wp-block-heading\" id=\"h-da-dies-zu-einfach-gewesen-ware-musste-ich-die-plakate-noch-einmal-umgestalten-da-die-formate-die-wir-am-abend-zuvor-extra-ausgemessen-und-angefragt-hatten-nun-doch-nicht-verfugbar-waren\">Da dies zu einfach gewesen w\u00e4re, musste ich die Plakate noch einmal umgestalten, da die Formate, die wir am Abend zuvor extra ausgemessen und angefragt hatten nun doch nicht verf\u00fcgbar waren.<\/h5>\n\n\n\n<p class=\"wp-block-paragraph\">Also setzte ich mich wortw\u00f6rtlich auf meinen Hosenboden, gestaltete wenige Minuten vor Messeer\u00f6ffnung neue Plakate und meine Eltern kamen schlie\u00dflich kurze Zeit sp\u00e4ter mit den Plakaten zur\u00fcck. Die Arbeit hatte sich gelohnt. Die Leute trauten sich nun auch selbstst\u00e4ndig unsere B\u00fccher aus dem Regal zu nehmen und durchzubl\u00e4ttern.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Auch jetzt haben wir mit unterschiedlichen Herausforderungen zu tun und das ist gut so. Denn ohne sie gibt es keine Entwicklung und kein Wachstum. Deshalb sind wir froh um jede Herausforderung, egal ob wir sie uns selbst setzen oder nicht und gehen diese stets mit der Divise an sie zu l\u00f6sen.<\/p>\n\n\n\n<h4 class=\"wp-block-heading\" id=\"h-was-macht-ihre-produkte-auf-dem-buchmarkt-einzigartig-und-welche-innovationen-bringen-sie-mit-sich\">Was macht Ihre Produkte auf dem Buchmarkt einzigartig und welche Innovationen bringen sie mit sich?<\/h4>\n\n\n\n<p class=\"wp-block-paragraph\">Unsere Fotocomics bestehen, wie der Name bereits verr\u00e4t, aus hochwertigen Farbfotografien, welche mit passenden Texten in comichaften Sprechblasen versehen sind. Sie werden stets in exklusiven Locations wie beispielsweise privaten Schl\u00f6ssern, Kl\u00f6stern, privaten und \u00f6ffentlichen Museen oder anderen besonderen R\u00e4umlichkeiten aufgenommen. Dar\u00fcber hinaus sind es aufgrund der Kombination aus Text und Fotografie die ersten barrierefreien B\u00fccher auf dem Markt. Denn dank der hochwertigen Farbfotografien, wird bereits die Wirklichkeit und die erz\u00e4hlende Szene abgebildet. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Das bedeutet, es m\u00fcssen keine Illustrationen, welche dar\u00fcber hinaus stets nur einen Bruchteil einer Szene darstellen, in unsere Realit\u00e4t \u00fcbersetzt werden. Es m\u00fcssen auch keine anstrengenden, langen Texte gelesen werden, welche anschlie\u00dfend mittels Vorstellungsverm\u00f6gen, im Kopf zum Leben erweckt werden m\u00fcssen. Dies hat zur Folge, dass die Freude am Lesen gest\u00e4rkt sowie das Vorstellungsverm\u00f6gen unterst\u00fctzt werden und keinerlei Einstiegsbarriere- wie oben beschrieben- besteht, sondern direkt in die Geschichte eingestiegen werden kann.<\/p>\n\n\n\n<h5 class=\"wp-block-heading\" id=\"h-das-erste-blinddatebook-hat-die-form-eines-marchens-erhalten\">Das erste Blinddatebook hat die Form eines M\u00e4rchens erhalten. <\/h5>\n\n\n\n<p class=\"wp-block-paragraph\">Das Prinzip des Blinddatebooks bedeutet, dass es weder Titel noch Klappentext gibt. Au\u00dferdem ist sein Text in kleine Abschnitte eingeteilt, welche jeweils mit passenden, kleinen Illustrationen versehen sind. Das macht das Lesen leichter und unterst\u00fctzt das Vorstellungsverm\u00f6gen, wodurch der Lesespa\u00df erh\u00f6ht wird. Dar\u00fcber hinaus inspiriert unser erstes Blinddatem\u00e4rchen sowohl Kinder als auch Erwachsene dazu mehr ihrem Herzen zu folgen und dadurch ein gl\u00fccklicheres Leben zu f\u00fchren.<\/p>\n\n\n\n<h5 class=\"wp-block-heading\" id=\"h-auch-unser-krauterbuch-ist-etwas-vollig-neues-es-ist-das-erste-nachschlagewerk-welches-dazu-gedacht-ist-schnellstmoglich-hilfe-zur-selbsthilfe-zu-bieten\">Auch unser Kr\u00e4uterbuch ist etwas v\u00f6llig Neues. Es ist das erste Nachschlagewerk, welches dazu gedacht ist, schnellstm\u00f6glich Hilfe zur Selbsthilfe zu bieten.<\/h5>\n\n\n\n<p class=\"wp-block-paragraph\">Dank einer klaren und einfachen Strukturierung und stark visuellen Konzeptionierung, sowie Konzentrierung auf das Wesentlichste aber auch die Einf\u00fchrung von zus\u00e4tzlichen, kapitelspezifischen Inhaltsverzeichnissen und einigen weiteren Hilfestellungen, hat man zum ersten Mal die M\u00f6glichkeit so schnell und einfach wie nur m\u00f6glich zu finden, wonach man gerade sucht.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Dar\u00fcber hinaus finden sich nat\u00fcrlich auch weitere Produktneuheiten, wie die ersten Vorlesevideos, das erste m\u00e4rchenhaftgestaltete Buchjournal und viele Projekte, die gerade in Bearbeitung sind aber nat\u00fcrlich ebenfalls innovativ und einzigartig sind!<\/p>\n\n\n\n<h4 class=\"wp-block-heading\" id=\"h-wie-sehen-sie-die-zukunftige-entwicklung-ihres-unternehmens-und-welche-neuen-produkte-oder-initiativen-planen-sie\">Wie sehen Sie die zuk\u00fcnftige Entwicklung Ihres Unternehmens und welche neuen Produkte oder Initiativen planen Sie?<\/h4>\n\n\n\n<p class=\"wp-block-paragraph\">Entsprechend der bisherigen Reaktionen auf unsere bereits erschienenen Produkte, sowie auch die bereits angek\u00fcndigten Produkte, sehen wir der Zukunft positiv entgegen.<br>Aktuell entsteht im Rahmen einer Kooperation mit K\u00e4the Kruse eine Sammlerpuppe, welche die Prinzessin aus unserem ersten Blinddate- M\u00e4rchen darstellt. Im Zuge zweier weiterer Kooperationen sind sowohl ein Kinderlied f\u00fcr unsere Kinder- Fotocomics, sowie ein illustriertes Kinderbuch mit einem speziellen Gimmick in Arbeit.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Au\u00dferdem entstehen bereits weitere inspirierende Blinddate- M\u00e4rchen, der erste \u201eCook and Crime\u201c, welcher den klassischen Krimi mit Rezepten zum Nachkochen vereint und \u00e4hnlich gestaltet ist, wie unsere Blinddates. Auch das erste Kinderbuchjournal ist gerade in der Entstehung, sowie die ersten Fotocomics f\u00fcr Erwachsene, weitere Vorlesevideos und autorengelesene H\u00f6rb\u00fccher. Erfahrungsgem\u00e4\u00df wird sich diese Liste im Nu um einige weitere Punkte erg\u00e4nzen, sodass man sich stets auf interessante Neuerscheinungen und Projekte unsererseits freuen darf.<\/p>\n\n\n\n<h4 class=\"wp-block-heading\" id=\"h-wie-sind-sie-auf-die-idee-fur-das-erste-echte-blinddatebook-gekommen-und-welche-reaktionen-haben-sie-darauf-erhalten\">Wie sind Sie auf die Idee f\u00fcr das erste echte Blinddatebook gekommen und welche Reaktionen haben Sie darauf erhalten?<\/h4>\n\n\n\n<p class=\"wp-block-paragraph\">Das Blinddatebook basiert auf der Werbeidee der gro\u00dfen Buchh\u00e4ndler, die vereinzelt B\u00fccher in Geschenkpapier eingewickelt haben, um Kunden dazu zu inspirieren auch mal B\u00fccher zu lesen, die sie normalerweise vermutlich nicht in die Hand nehmen w\u00fcrden; beispielsweise, weil ihnen das Cover, der Autor oder der Klappentext nicht gef\u00e4llt.<br>Dieses Konzept haben wir aufgegriffen und bei unserem M\u00e4rchen Klappentext und Cover komplett weggelassen. Lediglich das Design und die Aufschrift \u201eEs war einmal\u2026\u201c lassen darauf schlie\u00dfen, dass es sich um ein M\u00e4rchen handelt, doch worum es genau geht, ist auf den ersten Blick nicht erkennbar.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Die Aktion bei den Buchh\u00e4ndlern kam recht gut bei den Kunden an. Dementsprechend rechneten wir mit einer \u00e4hnlich guten Resonanz. Unsere Erwartungen wurden jedoch weit \u00fcbertroffen. Bereits bei der Leipziger Buchmesse, mit der wir offiziell in die \u00d6ffentlichkeit und Ver\u00f6ffentlichung unserer Werke gingen, wurden schon beim Kauf des ersten Blinddates Anfragen nach weiteren M\u00e4rchenblinddates gestellt.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Zudem zeigten uns auch die Verkaufszahlen, dass es, zusammen mit unserem Kr\u00e4uterbuch, mit gro\u00dfem Abstand das beliebteste Produkt in unserem damaligen Sortiment war (es hat sich seither bereits deutlich erweitert, wie oben beschrieben).<\/p>\n\n\n\n<h4 class=\"wp-block-heading\" id=\"h-inwiefern-tragen-ihre-fotocomics-fur-kinder-zur-barrierefreiheit-bei-und-warum-ist-ihnen-dieses-thema-so-wichtig\">Inwiefern tragen Ihre Fotocomics f\u00fcr Kinder zur Barrierefreiheit bei und warum ist Ihnen dieses Thema so wichtig?<\/h4>\n\n\n\n<p class=\"wp-block-paragraph\">Bei herk\u00f6mmlichen B\u00fcchern m\u00fcssen die Kinder die verwendeten Illustrationen in die Wirklichkeit \u00fcbersetzen. Dies erfordert ein gewisses Ma\u00df an Vorstellungskraft und Interesse an der Geschichte. Oder es m\u00fcssen zun\u00e4chst schlichte Schwarz- wei\u00df- Texte gelesen werden, was bereits die F\u00e4higkeit zu Lesen voraussetzt und ein gewisses Ma\u00df an Disziplin. Anschlie\u00dfend m\u00fcssen die Texte im Kopf zum Leben erweckt werden. Auch dies erfordert eine gewisse Vorstellungskraft. Beide klassischen Buchvarianten, die erstgenannten illustrierten Bilderb\u00fccher, als auch die normalen Kinderb\u00fccher\/ Kinderromane weisen die beschriebenen Einstiegsbarrieren auf. Das selbe Prinzip gilt \u00fcbrigens auch f\u00fcr Erwachsene (\u00fcbertragen auf beispielsweise Romane).<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Kinder, denen dies zu anstrengend ist, da sie dank der (in meinen Augen viel zu fr\u00fchen) Konfrontation mit der Digitalisierung keinerlei Anstrengung mehr unternehmen m\u00fcssen um den Konsum von Geschichten vornehmen zu k\u00f6nnen, da sie diese viel leichter als Spieleapp oder Serie anstrengungsfrei genie\u00dfen k\u00f6nnen, brauchen einen einfacheren und schnelleren Einstieg in die Geschichte, wie sie ihnen die Apps und Serien bieten, sowie einen h\u00f6heren Anreiz die Geschichte als Buch zu entdecken.&nbsp;<\/p>\n\n\n\n<h5 class=\"wp-block-heading\" id=\"h-wie-wichtig-und-aus-welchen-grunden-das-lesen-fur-menschen-jeglichen-alters-ist-muss-ich-wohl-nicht-weiter-ausfuhren\">Wie wichtig und aus welchen Gr\u00fcnden das Lesen f\u00fcr Menschen jeglichen Alters ist, muss ich wohl nicht weiter ausf\u00fchren. <\/h5>\n\n\n\n<p class=\"wp-block-paragraph\">Auch, dass, wie oben bereits angemerkt, die Digitalisierung und modernen \u201eErziehungsmethoden\u201c es immer schwieriger macht Kinder zum Lesen zu begeistern sollte den meisten klar sein.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Zu diesen allgemein wichtigen Punkten kommen jedoch noch weitere wichtige Aspekte hinzu, die sich aus unserem aktuellen Zeitgeschehen ergeben. So ist es wichtig den \u00fcberm\u00e4\u00dfigen Konsum von Geschichten mit Hilfe des Lesens etwas einzud\u00e4mmen, um dadurch die Reiz\u00fcberflutung und \u00dcberforderung der Kinder zu reduzieren. Die Gr\u00fcnde, weshalb der \u00fcberm\u00e4\u00dfige Konsum f\u00fcr Kinder und Erwachsene sch\u00e4dlich ist, ist ebenfalls schnell und einfach erkl\u00e4rt.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Durch den zu hohen Konsum entsteht Reiz\u00fcberflutung, woraus \u00dcberforderung und Stress entstehen. Diese haben weiter zur Folge, dass die eigenen Bed\u00fcrfnisse nicht mehr wahrgenommen werden k\u00f6nnen, da diese vom Konsumieren \u00fcbert\u00f6nt werden. Dass dies langfristig sowohl gesundheitssch\u00e4digend ist als auch gesellschaftliche Probleme nach sich zieht sollte f\u00fcr jeden leicht nachvollziehbar sein.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Aus diesen Gr\u00fcnden m\u00f6chten wir den Kindern und Eltern mit unseren B\u00fcchern nicht nur etwas Besonderes sondern auch eine Hilfestellung durch die Barrierefreiheit in unseren B\u00fcchern bieten, die es m\u00f6glich macht mit Leichtigkeit direkt in die Geschichte einzusteigen und mit Freude den Spa\u00df am Lesen f\u00fcr sich zu entdecken.<\/p>\n\n\n\n<h4 class=\"wp-block-heading\" id=\"h-konnen-sie-uns-mehr-uber-das-alltagstaugliche-nachschlagewerk-im-bereich-krauter-und-naturheilkunde-erzahlen-und-wie-es-den-nutzern-im-alltag-hilft\">K\u00f6nnen Sie uns mehr \u00fcber das alltagstaugliche Nachschlagewerk im Bereich Kr\u00e4uter- und Naturheilkunde erz\u00e4hlen und wie es den Nutzern im Alltag hilft?<\/h4>\n\n\n\n<p class=\"wp-block-paragraph\">Wer sich in dem Bereich der Kr\u00e4uter- und Naturheilkunde besch\u00e4ftigt wei\u00df, dass es zwar eine gro\u00dfe Masse an B\u00fcchern gibt, die meisten jedoch sehr \u00e4hnlichen oder gleichen Inhalt liefern. Vor allem aber sind sie alle nicht f\u00fcr den allt\u00e4glichen Gebrauch gedacht. Man muss die B\u00fccher mit den langen Textbl\u00f6cken durcharbeiten und anschlie\u00dfend stets ein eigenes Buch zum Nachschlagen erarbeiten. Doch auch bei den eigens geschriebenen B\u00fcchern hat man das gleiche Problem, wie bei den gekauften: man muss l\u00e4ngere Zeit suchen, um zu finden, was man aktuell ben\u00f6tigt. Auch das Prinzip der Haftnotizzettel, Textmarker und Randnotizen schafft letztlich keine Abhilfe mehr.<\/p>\n\n\n\n<h5 class=\"wp-block-heading\" id=\"h-aus-diesem-grund-haben-wir-unser-krauterbuch-entwickelt-es-ist-ein-alltagshelfer-fur-das-einfache-und-schnelle-nachschlagen-damit-es-so-ubersichtlich-und-einfach-wie-nur-irgendwie-moglich-ist-gibt-es-drei-grosse-hauptrubriken\">Aus diesem Grund haben wir unser Kr\u00e4uterbuch entwickelt. Es ist ein Alltagshelfer f\u00fcr das einfache und schnelle Nachschlagen. Damit es so \u00fcbersichtlich und einfach, wie nur irgendwie m\u00f6glich ist, gibt es drei gro\u00dfe Hauptrubriken:<\/h5>\n\n\n\n<p class=\"wp-block-paragraph\">1. Allgemeines + Monatssammelplan zum Selbersammeln<br>2. Rezepte<br>3. Krankheiten und Beschwerden.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Dadurch kann bereits recht einfach und z\u00fcgig gefunden werden wonach man sucht, denn f\u00fcr gew\u00f6hnlich ben\u00f6tigt man entweder ein Rezept oder Vorschl\u00e4ge an Hilfsmitteln, die bei einer konkreten Beschwerde helfen k\u00f6nnen. Da uns dies jedoch nicht reicht, ist das Buch sehr visuell aufgebaut, wodurch man sich noch schneller und einfacher zurechtfinden kann.<br>Als weitere Hilfestellung ist jeder Kapitelinhalt alphabetisch sortiert.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Jede Seite hat oben am \u00e4u\u00dferen Seitenrand farbliche Markierungen, die mit kurzen Stichworten beschreibt, was auf der Seite zu finden ist. Jedes Kapitel hat zu Beginn ein eigenes Zusatzinhaltsverzeichnis, erg\u00e4nzend zum klassischen Inhaltsverzeichnis, welches sich am Buchanfang befindet. Dieses zus\u00e4tzliche Inhaltsverzeichnis gibt einen \u00dcberblick \u00fcber das entsprechende Kapitel, sodass nicht immer im gro\u00dfen Inhaltsverzeichnis gesucht werden muss.<\/p>\n\n\n\n<h5 class=\"wp-block-heading\" id=\"h-alle-texte-sind-auf-das-wichtigste-heruntergekurzt-es-mussen-also-keine-textblocke-mehr-gelesen-werden-sondern-es-kann-auf-einen-blick-alles-notige-erfasst-werden-was-man-wissen-muss\">Alle Texte sind auf das Wichtigste heruntergek\u00fcrzt. Es m\u00fcssen also keine Textbl\u00f6cke mehr gelesen werden, sondern es kann auf einen Blick alles N\u00f6tige erfasst werden, was man wissen muss.<\/h5>\n\n\n\n<p class=\"wp-block-paragraph\">Sucht man unter den Krankheiten bekommt man zwei Wahlm\u00f6glichkeiten:<br>\u201eHelfende Mittel\u201c und \u201eHelfende Pflanzen\u201c. Unter der Kategorie \u201ehelfende Mittel\u201c findet man bereits fertige Hilfsmittel, wie beispielsweise Tee- Vorschl\u00e4ge. Unter \u201ehelfende Pflanzen\u201c findet man lediglich Pflanzenvorschl\u00e4ge. Diese unterscheiden sich von den \u201ehelfenden Mittel\u201c und bieten nicht nur andere M\u00f6glichkeiten, sondern auch die M\u00f6glichkeit, dass man selbst entscheiden kann, was man aus den vorgeschlagenen Pflanzen machen m\u00f6chte- Tee, Salbe, Tinktur, Kr\u00e4uterkissen, Umschlag, \u2026<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Entscheidet man sich dazu ein \u201ehelfendes Mittel\u201c anzuwenden und m\u00f6chte dies nicht kaufen sondern selbst herstellen, so findet man neben dem herausgesuchten Mittel eine Seitenangabe unter der man das gew\u00fcnschte Rezept findet um das Mittel selbst herzustellen oder nochmal nachzusehen ob bei der Einnahme etwas Bestimmtes beachtet werden muss.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Durch das oben beschriebene Konzept aber auch durch das geballte Wissen, welches aus \u00fcber 100 verschiedenen Kr\u00e4uterb\u00fcchern (sowohl \u00e4lteren als auch neueren) zusammengetragen und sorgf\u00e4ltig abgew\u00e4gt und getestet wurde, entsteht der gr\u00f6\u00dftm\u00f6gliche Nutzen f\u00fcr den Anwender. Dar\u00fcber hinaus erg\u00e4nzt der Einf\u00fchrungsteil mit interessanten und hilfreichen Tipps, wodurch das Buch f\u00fcr Anf\u00e4nger aber auch Fortgeschrittene hervorragend geeignet ist.<\/p>\n\n\n\n<h4 class=\"wp-block-heading\" id=\"h-was-wurden-sie-anderen-grundern-als-drei-wichtigste-ratschlage-auf-den-weg-geben\">Was w\u00fcrden Sie anderen Gr\u00fcndern als drei wichtigste Ratschl\u00e4ge auf den Weg geben?<\/h4>\n\n\n\n<ol class=\"wp-block-list\">\n<li>K\u00fcmmert euch lieber zu fr\u00fch als zu sp\u00e4t um PR und Marketing.<\/li>\n\n\n\n<li>Lasst euch von anderen nicht zu sehr reinreden. Folgt lieber eurem Herzen, das kennt den Weg f\u00fcr gew\u00f6hnlich besser als die meisten Mitmenschen.<\/li>\n\n\n\n<li>Es ist immer gut sich nicht nur auf seinen Markt\/ Nische\/ Branche zu beschr\u00e4nken. Gerade auch andere M\u00e4rkte k\u00f6nnen allerhand Inspiration oder sogar Kooperationsm\u00f6glichkeiten bieten und damit eine Bereicherung und Weiterentwicklung sowohl f\u00fcr euch selbst als auch euer Unternehmen darstellen.<\/li>\n<\/ol>\n\n\n\n<h4 class=\"wp-block-heading\" id=\"h-wie-haben-sie-es-geschafft-ihre-produkte-auf-der-leipziger-buchmesse-erfolgreich-zu-prasentieren-und-welche-resonanz-haben-sie-dort-erfahren\">Wie haben Sie es geschafft, Ihre Produkte auf der Leipziger Buchmesse erfolgreich zu pr\u00e4sentieren und welche Resonanz haben Sie dort erfahren?<\/h4>\n\n\n\n<p class=\"wp-block-paragraph\">Wir richten uns stets nicht zu sehr nach der Konkurrenz. Da wir uns auch aus Zeitmangel nicht weiter \u00fcber die Buchmesse genauer informiert haben, haben wir einfach nur unser Ding durchgezogen und nach Gef\u00fchl und eigenen Vorstellungen gehandelt, wie wir es meistens tun. Dementsprechend haben wir unseren Stand auch sehr liebevoll und relativ detailverliebt gestaltet.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Dies f\u00fchrte, wie oben bereits angesprochen zun\u00e4chst dazu, dass sich einige nicht an unseren Stand herantrauten, da er \u201ezu sch\u00f6n\u201c (Zitat von vielen Messebesuchern) war.<br>Durch die nachger\u00fcsteten Plakate, die unserem Stil entsprechend zu unseren B\u00fcchern und unserem Stand passten, schufen wir z\u00fcgig die n\u00f6tige Abhilfe.<\/p>\n\n\n\n<h5 class=\"wp-block-heading\" id=\"h-die-beiden-wichtigsten-lernfaktoren-und-erlebnisse-der-messe-waren-fur-uns-die-folgenden-zwei\">Die beiden wichtigsten Lernfaktoren und Erlebnisse der Messe waren f\u00fcr uns die folgenden zwei:<\/h5>\n\n\n\n<p class=\"wp-block-paragraph\">1. Die Aussteller sind untereinander meist gut befreundet und betrachten sich nicht als<br>&nbsp; &nbsp; Konkurrenz, sondern als Familie, in der man sich gegenseitig stets gerne hilft! Au\u00dferdem<br>&nbsp; &nbsp; ist es ratsam und hilfreich sich mit den anderen Ausstellern zu vernetzen und<br>&nbsp; &nbsp; auszutauschen. Da der Zusammenhalt und die gute Laune gegeben waren, war auch die<br>&nbsp; &nbsp; Atmosph\u00e4re entsprechend angenehm.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">2. Neue Produkte bed\u00fcrfen entsprechender Erkl\u00e4rungen- selbst bei einem Buch.<br>&nbsp; &nbsp; Dies war f\u00fcr mich jedoch eine wichtige Erkenntnis in Bezug auf das Marketing und<br>&nbsp; &nbsp; weitere Herantreten an\/ Auftreten auf dem Markt.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Am Ende l\u00e4sst sich sagen, dass sowohl Mitbewerber als auch Kunden begeistert und beeindruckt von unseren Innovationen und Qualit\u00e4t waren und sich bereits auf die kommenden Produkte freuten.<\/p>\n\n\n\n<h4 class=\"wp-block-heading\" id=\"h-wie-stellen-sie-sicher-dass-ihre-bucher-sowohl-fur-sehr-junge-kinder-als-auch-fur-erstleser-ansprechend-und-lehrreich-sind\">Wie stellen Sie sicher, dass Ihre B\u00fccher sowohl f\u00fcr sehr junge Kinder als auch f\u00fcr Erstleser ansprechend und lehrreich sind?<\/h4>\n\n\n\n<p class=\"wp-block-paragraph\">Unsere Fotocomics f\u00fcr Kinder k\u00f6nnen aufgrund der Gestaltung als Bilderbuch zum Vorlesen verwendet werden. Da die Gestaltung allerdings dank der neuen Kombination von hochwertigen Farbfotografien interessant ist spricht sie auch \u00e4ltere Kinder an. Die liebevolle Detailverliebtheit unserer Fotografien macht es zudem m\u00f6glich, dass die Geschichte immer wieder durchgebl\u00e4ttert und dennoch immer wieder neue Details entdeckt werden k\u00f6nnen. Da die Geschichten einfach aber nicht langweilig und die Texte einfach sowie kurz gehalten sind sprechen sie ebenfalls sowohl Kleinkinder als auch Erstleser an.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Auch unser s\u00fc\u00dfer und liebevoller Protagonist Sir Hops der (Oster-) Hase wird ebenfalls von j\u00fcngeren, wie auch \u00e4lteren Kindern sofort ins Herz geschlossen.<br>Zu guter Letzt bietet die Frage was der Osterhase au\u00dferhalb der Osterzeit so treibt,<br>gerade \u00e4lteren Kindern (Erstlesern) einen interessanten Anreiz, die Geschichte f\u00fcr sich selbst zu entdecken und die Frage zu beantworten.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Bild@privat<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Wir bedanken uns bei <a href=\"https:\/\/www.linkedin.com\/in\/vanessablo%C3%9F\/\" target=\"_blank\" rel=\"noreferrer noopener\">Vanessa Blo\u00df<\/a>&nbsp;f\u00fcr das Interview<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Aussagen des Autors und des Interviewpartners geben nicht unbedingt die Meinung der Redaktion und des Verlags wieder.<\/p>\n\n\n\n<ul class=\"wp-block-yoast-seo-related-links yoast-seo-related-links\">\n<li><a href=\"https:\/\/startupvalley.news\/de\/sollso\/\">Sollso: Carbon Laufrad f\u00fcr Erwachsene<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/startupvalley.news\/de\/xeem-open-innovation-recruting\/\">Habe den Mut, die ersten Schritte zu gehen<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/startupvalley.news\/de\/aw-academy-schule-erwachsene\/\">Es ist wichtig \u00fcber Fehler und Erfolge nachzudenken<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/startupvalley.news\/de\/getmobie-finanzielle-bildung-banking\/\">Lernt aus euren Fehlern<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/startupvalley.news\/de\/faio\/\">Vorbereitung und Authentizit\u00e4t sind entscheidend<\/a><\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>Kunstimperium bringt mit innovativen, hochwertigen B\u00fcchern und Fotocomics neuen Schwung in die Welt des Lesens und f\u00f6rdert die Freude an Geschichten f\u00fcr alle Altersgruppen<\/p>\n","protected":false},"author":9,"featured_media":107503,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[6430,26473],"tags":[4633,4030,7288],"class_list":["post-107502","post","type-post","status-publish","format-standard","has-post-thumbnail","category-female-founders","category-interviews","tag-buecher","tag-hoerbuecher","tag-kreativitaet"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.3 (Yoast SEO v28.3) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Kunstimperium: Vielf\u00e4ltige Kreativit\u00e4t f\u00fcr alle Altersgruppen - StartupValley<\/title>\n<meta name=\"description\" content=\"Entdecken Sie das Kunstimperium: eine kreative Oase f\u00fcr B\u00fccher, Vorlesevideos und autorengelesene H\u00f6rb\u00fccher.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/startupvalley.news\/de\/kunstimperium\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"K\u00f6nnte dies die perfekte L\u00f6sung f\u00fcr Lesemuffel sein?\" \/>\n<meta property=\"og:description\" content=\"Entdecken Sie das Kunstimperium: eine kreative Oase f\u00fcr B\u00fccher, Vorlesevideos und autorengelesene H\u00f6rb\u00fccher.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/startupvalley.news\/de\/kunstimperium\/\" \/>\n<meta property=\"og:site_name\" content=\"StartupValley\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/startupvalleynews\" \/>\n<meta property=\"article:published_time\" content=\"2024-08-01T08:19:47+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-06-11T06:24:48+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/startupvalley.news\/de\/wp-content\/uploads\/sites\/2\/2024\/07\/kunstimperium.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"675\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"StartupValley\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@startup_valley\" \/>\n<meta name=\"twitter:site\" content=\"@startup_valley\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"StartupValley\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"18\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\\\/\\\/startupvalley.news\\\/de\\\/kunstimperium\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/startupvalley.news\\\/de\\\/kunstimperium\\\/\"},\"author\":{\"name\":\"StartupValley\",\"@id\":\"https:\\\/\\\/startupvalley.news\\\/de\\\/#\\\/schema\\\/person\\\/dc9abc71daa8d949d4f257f2e9883e00\"},\"headline\":\"K\u00f6nnte dies die perfekte L\u00f6sung f\u00fcr Lesemuffel sein?\",\"datePublished\":\"2024-08-01T08:19:47+00:00\",\"dateModified\":\"2026-06-11T06:24:48+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/startupvalley.news\\\/de\\\/kunstimperium\\\/\"},\"wordCount\":3430,\"publisher\":{\"@id\":\"https:\\\/\\\/startupvalley.news\\\/de\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/startupvalley.news\\\/de\\\/kunstimperium\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/startupvalley.news\\\/de\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2024\\\/07\\\/kunstimperium.jpg\",\"keywords\":[\"B\u00fccher\",\"H\u00f6rb\u00fccher\",\"Kreativit\u00e4t\"],\"articleSection\":[\"Female Founders\",\"Interviews\"],\"inLanguage\":\"de\",\"copyrightYear\":\"2024\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/startupvalley.news\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/startupvalley.news\\\/de\\\/kunstimperium\\\/\",\"url\":\"https:\\\/\\\/startupvalley.news\\\/de\\\/kunstimperium\\\/\",\"name\":\"Kunstimperium: Vielf\u00e4ltige Kreativit\u00e4t f\u00fcr alle Altersgruppen - StartupValley\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/startupvalley.news\\\/de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/startupvalley.news\\\/de\\\/kunstimperium\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/startupvalley.news\\\/de\\\/kunstimperium\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/startupvalley.news\\\/de\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2024\\\/07\\\/kunstimperium.jpg\",\"datePublished\":\"2024-08-01T08:19:47+00:00\",\"dateModified\":\"2026-06-11T06:24:48+00:00\",\"description\":\"Entdecken Sie das Kunstimperium: eine kreative Oase f\u00fcr B\u00fccher, Vorlesevideos und autorengelesene H\u00f6rb\u00fccher.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/startupvalley.news\\\/de\\\/kunstimperium\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/startupvalley.news\\\/de\\\/kunstimperium\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/startupvalley.news\\\/de\\\/kunstimperium\\\/#primaryimage\",\"url\":\"https:\\\/\\\/startupvalley.news\\\/de\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2024\\\/07\\\/kunstimperium.jpg\",\"contentUrl\":\"https:\\\/\\\/startupvalley.news\\\/de\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2024\\\/07\\\/kunstimperium.jpg\",\"width\":1200,\"height\":675,\"caption\":\"kunstimperium gr\u00fcnderinnen Mutter Tanja und ihrer Tochter Vanessa Blo\u00df\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/startupvalley.news\\\/de\\\/kunstimperium\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/startupvalley.news\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"K\u00f6nnte dies die perfekte L\u00f6sung f\u00fcr Lesemuffel sein?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/startupvalley.news\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/startupvalley.news\\\/de\\\/\",\"name\":\"StartupValley\",\"description\":\"Startup-News, Funding &amp; Gr\u00fcnder-Interviews\",\"publisher\":{\"@id\":\"https:\\\/\\\/startupvalley.news\\\/de\\\/#organization\"},\"alternateName\":\"StartupValley Magazin\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/startupvalley.news\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/startupvalley.news\\\/de\\\/#organization\",\"name\":\"StartupValley Media\",\"url\":\"https:\\\/\\\/startupvalley.news\\\/de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/startupvalley.news\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/startupvalley.news\\\/de\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2020\\\/12\\\/StartupValley-LOGO-neu-retina.png\",\"contentUrl\":\"https:\\\/\\\/startupvalley.news\\\/de\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2020\\\/12\\\/StartupValley-LOGO-neu-retina.png\",\"width\":460,\"height\":180,\"caption\":\"StartupValley Media\"},\"image\":{\"@id\":\"https:\\\/\\\/startupvalley.news\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/startupvalleynews\",\"https:\\\/\\\/x.com\\\/startup_valley\",\"https:\\\/\\\/www.twitch.tv\\\/startupvalley\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/startupvalleymagazine\",\"https:\\\/\\\/www.instagram.com\\\/startup_valley\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/startupvalley.news\\\/de\\\/#\\\/schema\\\/person\\\/dc9abc71daa8d949d4f257f2e9883e00\",\"name\":\"StartupValley\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6436ca57465a88bfa716825ebdd3bc23f850aaaa3a51d16da34504822452fa3a?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6436ca57465a88bfa716825ebdd3bc23f850aaaa3a51d16da34504822452fa3a?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6436ca57465a88bfa716825ebdd3bc23f850aaaa3a51d16da34504822452fa3a?s=96&d=mm&r=g\",\"caption\":\"StartupValley\"},\"description\":\"Das StartupValley Magazin ist Europas gro\u00dfes Magazin f\u00fcr Start-ups, Gr\u00fcnder und Entrepreneure. Ihr findet bei uns Tagesaktuelle News zu den neuesten Trends, Technologien und Gesch\u00e4ftsmodellen der internationalen Startup-Szene sowie Interviews mit erfolgreichen Gr\u00fcndern und Investoren.\",\"url\":\"https:\\\/\\\/startupvalley.news\\\/de\\\/author\\\/redaktion\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Kunstimperium: Vielf\u00e4ltige Kreativit\u00e4t f\u00fcr alle Altersgruppen - StartupValley","description":"Entdecken Sie das Kunstimperium: eine kreative Oase f\u00fcr B\u00fccher, Vorlesevideos und autorengelesene H\u00f6rb\u00fccher.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/startupvalley.news\/de\/kunstimperium\/","og_locale":"de_DE","og_type":"article","og_title":"K\u00f6nnte dies die perfekte L\u00f6sung f\u00fcr Lesemuffel sein?","og_description":"Entdecken Sie das Kunstimperium: eine kreative Oase f\u00fcr B\u00fccher, Vorlesevideos und autorengelesene H\u00f6rb\u00fccher.","og_url":"https:\/\/startupvalley.news\/de\/kunstimperium\/","og_site_name":"StartupValley","article_publisher":"https:\/\/www.facebook.com\/startupvalleynews","article_published_time":"2024-08-01T08:19:47+00:00","article_modified_time":"2026-06-11T06:24:48+00:00","og_image":[{"width":1200,"height":675,"url":"https:\/\/startupvalley.news\/de\/wp-content\/uploads\/sites\/2\/2024\/07\/kunstimperium.jpg","type":"image\/jpeg"}],"author":"StartupValley","twitter_card":"summary_large_image","twitter_creator":"@startup_valley","twitter_site":"@startup_valley","twitter_misc":{"Verfasst von":"StartupValley","Gesch\u00e4tzte Lesezeit":"18\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/startupvalley.news\/de\/kunstimperium\/#article","isPartOf":{"@id":"https:\/\/startupvalley.news\/de\/kunstimperium\/"},"author":{"name":"StartupValley","@id":"https:\/\/startupvalley.news\/de\/#\/schema\/person\/dc9abc71daa8d949d4f257f2e9883e00"},"headline":"K\u00f6nnte dies die perfekte L\u00f6sung f\u00fcr Lesemuffel sein?","datePublished":"2024-08-01T08:19:47+00:00","dateModified":"2026-06-11T06:24:48+00:00","mainEntityOfPage":{"@id":"https:\/\/startupvalley.news\/de\/kunstimperium\/"},"wordCount":3430,"publisher":{"@id":"https:\/\/startupvalley.news\/de\/#organization"},"image":{"@id":"https:\/\/startupvalley.news\/de\/kunstimperium\/#primaryimage"},"thumbnailUrl":"https:\/\/startupvalley.news\/de\/wp-content\/uploads\/sites\/2\/2024\/07\/kunstimperium.jpg","keywords":["B\u00fccher","H\u00f6rb\u00fccher","Kreativit\u00e4t"],"articleSection":["Female Founders","Interviews"],"inLanguage":"de","copyrightYear":"2024","copyrightHolder":{"@id":"https:\/\/startupvalley.news\/#organization"}},{"@type":"WebPage","@id":"https:\/\/startupvalley.news\/de\/kunstimperium\/","url":"https:\/\/startupvalley.news\/de\/kunstimperium\/","name":"Kunstimperium: Vielf\u00e4ltige Kreativit\u00e4t f\u00fcr alle Altersgruppen - StartupValley","isPartOf":{"@id":"https:\/\/startupvalley.news\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/startupvalley.news\/de\/kunstimperium\/#primaryimage"},"image":{"@id":"https:\/\/startupvalley.news\/de\/kunstimperium\/#primaryimage"},"thumbnailUrl":"https:\/\/startupvalley.news\/de\/wp-content\/uploads\/sites\/2\/2024\/07\/kunstimperium.jpg","datePublished":"2024-08-01T08:19:47+00:00","dateModified":"2026-06-11T06:24:48+00:00","description":"Entdecken Sie das Kunstimperium: eine kreative Oase f\u00fcr B\u00fccher, Vorlesevideos und autorengelesene H\u00f6rb\u00fccher.","breadcrumb":{"@id":"https:\/\/startupvalley.news\/de\/kunstimperium\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/startupvalley.news\/de\/kunstimperium\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/startupvalley.news\/de\/kunstimperium\/#primaryimage","url":"https:\/\/startupvalley.news\/de\/wp-content\/uploads\/sites\/2\/2024\/07\/kunstimperium.jpg","contentUrl":"https:\/\/startupvalley.news\/de\/wp-content\/uploads\/sites\/2\/2024\/07\/kunstimperium.jpg","width":1200,"height":675,"caption":"kunstimperium gr\u00fcnderinnen Mutter Tanja und ihrer Tochter Vanessa Blo\u00df"},{"@type":"BreadcrumbList","@id":"https:\/\/startupvalley.news\/de\/kunstimperium\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/startupvalley.news\/de\/"},{"@type":"ListItem","position":2,"name":"K\u00f6nnte dies die perfekte L\u00f6sung f\u00fcr Lesemuffel sein?"}]},{"@type":"WebSite","@id":"https:\/\/startupvalley.news\/de\/#website","url":"https:\/\/startupvalley.news\/de\/","name":"StartupValley","description":"Startup-News, Funding &amp; Gr\u00fcnder-Interviews","publisher":{"@id":"https:\/\/startupvalley.news\/de\/#organization"},"alternateName":"StartupValley Magazin","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/startupvalley.news\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/startupvalley.news\/de\/#organization","name":"StartupValley Media","url":"https:\/\/startupvalley.news\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/startupvalley.news\/de\/#\/schema\/logo\/image\/","url":"https:\/\/startupvalley.news\/de\/wp-content\/uploads\/sites\/2\/2020\/12\/StartupValley-LOGO-neu-retina.png","contentUrl":"https:\/\/startupvalley.news\/de\/wp-content\/uploads\/sites\/2\/2020\/12\/StartupValley-LOGO-neu-retina.png","width":460,"height":180,"caption":"StartupValley Media"},"image":{"@id":"https:\/\/startupvalley.news\/de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/startupvalleynews","https:\/\/x.com\/startup_valley","https:\/\/www.twitch.tv\/startupvalley","https:\/\/www.linkedin.com\/company\/startupvalleymagazine","https:\/\/www.instagram.com\/startup_valley"]},{"@type":"Person","@id":"https:\/\/startupvalley.news\/de\/#\/schema\/person\/dc9abc71daa8d949d4f257f2e9883e00","name":"StartupValley","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/6436ca57465a88bfa716825ebdd3bc23f850aaaa3a51d16da34504822452fa3a?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/6436ca57465a88bfa716825ebdd3bc23f850aaaa3a51d16da34504822452fa3a?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/6436ca57465a88bfa716825ebdd3bc23f850aaaa3a51d16da34504822452fa3a?s=96&d=mm&r=g","caption":"StartupValley"},"description":"Das StartupValley Magazin ist Europas gro\u00dfes Magazin f\u00fcr Start-ups, Gr\u00fcnder und Entrepreneure. Ihr findet bei uns Tagesaktuelle News zu den neuesten Trends, Technologien und Gesch\u00e4ftsmodellen der internationalen Startup-Szene sowie Interviews mit erfolgreichen Gr\u00fcndern und Investoren.","url":"https:\/\/startupvalley.news\/de\/author\/redaktion\/"}]}},"_links":{"self":[{"href":"https:\/\/startupvalley.news\/de\/wp-json\/wp\/v2\/posts\/107502","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/startupvalley.news\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/startupvalley.news\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/startupvalley.news\/de\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/startupvalley.news\/de\/wp-json\/wp\/v2\/comments?post=107502"}],"version-history":[{"count":3,"href":"https:\/\/startupvalley.news\/de\/wp-json\/wp\/v2\/posts\/107502\/revisions"}],"predecessor-version":[{"id":119005,"href":"https:\/\/startupvalley.news\/de\/wp-json\/wp\/v2\/posts\/107502\/revisions\/119005"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/startupvalley.news\/de\/wp-json\/wp\/v2\/media\/107503"}],"wp:attachment":[{"href":"https:\/\/startupvalley.news\/de\/wp-json\/wp\/v2\/media?parent=107502"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/startupvalley.news\/de\/wp-json\/wp\/v2\/categories?post=107502"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/startupvalley.news\/de\/wp-json\/wp\/v2\/tags?post=107502"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}