{"id":112307,"date":"2025-03-01T09:57:00","date_gmt":"2025-03-01T08:57:00","guid":{"rendered":"https:\/\/startupvalley.news\/de\/?p=112307"},"modified":"2025-09-30T08:33:18","modified_gmt":"2025-09-30T06:33:18","slug":"deal-sun-minimeal","status":"publish","type":"post","link":"https:\/\/startupvalley.news\/de\/deal-sun-minimeal\/","title":{"rendered":"Spektakul\u00e4rer Deal bei 2 Minuten 2 Millionen"},"content":{"rendered":"\n<h2 class=\"wp-block-heading\" id=\"h-rekord-deal-bei-2-minuten-2-millionen-start-up-sun-minimeal-sichert-sich-millionen-investment\"><strong>Rekord Deal bei \u201e2 Minuten 2 Millionen\u201c: Start-up \u201eSUN Minimeal\u201c sichert sich Millionen-Investment<\/strong><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Die aktuelle Staffel der erfolgreichen TV-Show \u201e<a href=\"https:\/\/startupvalley.news\/de\/27-februar-2025\/\" target=\"_blank\" rel=\"noreferrer noopener\">2 Minuten 2 Millionen<\/a>\u201c sorgt f\u00fcr Schlagzeilen. Bereits in der zweiten Folge wurde ein neuer Investment-Rekord aufgestellt. Das Start-up \u201eSUN Minimeal\u201c \u00fcberzeugte nicht nur die Jury mit seinem innovativen Snack-Konzept, sondern l\u00f6ste auch eine regelrechte Bieterschlacht unter den Investoren aus. Am Ende sicherte sich der Tiroler Unternehmer Christian J\u00e4ger den Deal und investierte die bislang h\u00f6chste Summe in der Geschichte der Sendung.<\/p>\n\n\n\n<h4 class=\"wp-block-heading\" id=\"h-ein-pitch-mit-historischem-ausgang\">Ein Pitch mit historischem Ausgang<\/h4>\n\n\n\n<p class=\"wp-block-paragraph\">Als <a href=\"https:\/\/www.linkedin.com\/in\/sun-minimeal\/\" target=\"_blank\" rel=\"noreferrer noopener\">Wolfgang Grabher<\/a>, Gr\u00fcnder von \u201eSUN Minimeal\u201c, gemeinsam mit seiner Frau Maike die B\u00fchne betrat, h\u00e4tte wohl niemand mit einem derartigen Verhandlungsmarathon gerechnet. Schon mit seinem humorvollen Einstieg \u2013 \u201eWir haben schon nach einer Show gesucht, die \u201a4 Minuten 4 Millionen\u2018 hei\u00dft\u201c \u2013 konnte der Vorarlberger Gr\u00fcnder die Business-Angels f\u00fcr sich gewinnen. Doch nicht nur die Pr\u00e4sentation, sondern vor allem das Produkt selbst beeindruckte: Die Minimeals sind die ersten essfertigen, n\u00e4hrstoffkompletten Mahlzeiten f\u00fcr unterwegs, die in jede Hosentasche passen. Eine gesunde Alternative zu herk\u00f6mmlichen Snacks, frei von Zucker und auf rein pflanzlicher Basis.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Dass die Idee zukunftsweisend ist, sahen auch die Investoren. Besonders Christian J\u00e4ger zeigte sich von der Innovation \u00fcberzeugt und ging volles Risiko: Er bot dem Gr\u00fcnderteam unglaubliche 4 Millionen Euro f\u00fcr 7,5 Prozent der Firmenanteile \u2013 ein Investment, das es in dieser H\u00f6he bislang noch nie in der Sendung gegeben hat. Damit stach er seinen Mitbewerber Mathias Muther aus, der sich ebenfalls f\u00fcr die Unternehmensbeteiligung interessierte. Der Deal markiert einen Meilenstein in der Geschichte von \u201e2 Minuten 2 Millionen\u201c und setzt neue Ma\u00dfst\u00e4be f\u00fcr zuk\u00fcnftige Investments in der Show.<\/p>\n\n\n\n<h4 class=\"wp-block-heading\" id=\"h-ein-weiterer-erfolg-das-tchibo-start-up-ticket\">Ein weiterer Erfolg: Das Tchibo-Start-up-Ticket<\/h4>\n\n\n\n<p class=\"wp-block-paragraph\">Neben dem Millionen-Deal gab es f\u00fcr das Ehepaar Grabher eine weitere erfreuliche Nachricht. Sie konnten sich eines der begehrten Tchibo-Start-up-Tickets von Investorin Charlotte Braunstorfer sichern. Diese Partnerschaft er\u00f6ffnet dem jungen Unternehmen zus\u00e4tzliche Vertriebsm\u00f6glichkeiten und Reichweite. Das bedeutet, dass \u201eSUN Minimeal\u201c k\u00fcnftig in den Filialen des internationalen Handelsunternehmens vertreten sein wird \u2013 ein enormer Schub f\u00fcr die Marktpr\u00e4senz und das Wachstum des Start-ups.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201eWir sind \u00fcberw\u00e4ltigt von der positiven Resonanz und freuen uns darauf, mit Christian J\u00e4ger als Partner die n\u00e4chste Wachstumsphase unseres Unternehmens einzuleiten. Mit der Unterst\u00fctzung von Tchibo wird es uns zudem m\u00f6glich sein, unsere Produkte noch schneller und breiter zug\u00e4nglich zu machen\u201c, erkl\u00e4rt Wolfgang Grabher nach der Sendung.<\/p>\n\n\n\n<h4 class=\"wp-block-heading\" id=\"h-was-macht-sun-minimeal-so-besonders\">Was macht \u201eSUN Minimeal\u201c so besonders?<\/h4>\n\n\n\n<p class=\"wp-block-paragraph\">Die Idee hinter \u201eSUN Minimeal\u201c ist ebenso simpel wie genial: Eine vollwertige, gesunde Mahlzeit in kompakter Form f\u00fcr unterwegs. Die Snacks enthalten alle essenziellen N\u00e4hrstoffe, sind pflanzenbasiert und frei von k\u00fcnstlichen Zusatzstoffen. Damit richtet sich das Produkt insbesondere an ern\u00e4hrungsbewusste Menschen, die auch in hektischen Alltagssituationen nicht auf eine gesunde Ern\u00e4hrung verzichten m\u00f6chten. Mit \u201eSUN Minimeal\u201c k\u00f6nnen Konsumenten eine Alternative zu ungesunden Zwischenmahlzeiten oder kalorienreichen Fast-Food-Gerichten w\u00e4hlen \u2013 eine Innovation, die genau den Nerv der Zeit trifft.<\/p>\n\n\n\n<h4 class=\"wp-block-heading\" id=\"h-erfolgreicher-abend-fur-die-tv-sender-der-prosiebensat-1-puls-4-gruppe\">Erfolgreicher Abend f\u00fcr die TV-Sender der ProSiebenSat.1 PULS 4 Gruppe<\/h4>\n\n\n\n<p class=\"wp-block-paragraph\">Die spektakul\u00e4re zweite Folge von \u201e2 Minuten 2 Millionen\u201c war nicht nur f\u00fcr \u201eSUN Minimeal\u201c ein Erfolg, sondern auch f\u00fcr die TV-Sender der ProSiebenSat.1 PULS 4 Gruppe. Die Show erfreut sich in \u00d6sterreich seit Jahren gro\u00dfer Beliebtheit und verzeichnet kontinuierlich steigende Zuschauerzahlen.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Um der wachsenden Nachfrage gerecht zu werden, hat die Sendergruppe nun beschlossen, ihr Show-Angebot weiter auszubauen. Ab dem 11. M\u00e4rz wird \u201e2 Minuten 2 Millionen\u201c zus\u00e4tzlich auch dienstags um 20:15 Uhr ausgestrahlt. Direkt im Anschluss folgt eine neue Folge von \u201eThe Biggest Loser\u201c, dem h\u00e4rtesten Abnehm-Camp. Donnerstags hingegen k\u00f6nnen sich die Zuschauer:innen auf das Kult-Format \u201eMein Gemeindebau\u201c bei ATV freuen. Auch das internationale Erfolgsformat \u201eGermany\u2019s Next Topmodel\u201c bleibt ein fester Bestandteil des Programms und wird weiterhin mittwochs und donnerstags auf ProSieben Austria ausgestrahlt.<\/p>\n\n\n\n<h4 class=\"wp-block-heading\" id=\"h-ausblick-wie-geht-es-fur-sun-minimeal-weiter\">Ausblick: Wie geht es f\u00fcr \u201eSUN Minimeal\u201c weiter?<\/h4>\n\n\n\n<p class=\"wp-block-paragraph\">Nach dem erfolgreichen Pitch beginnt f\u00fcr Wolfgang und Maike Grabher nun die n\u00e4chste gro\u00dfe Herausforderung: die Umsetzung des Wachstumsplans. Mit dem Millioneninvestment von Christian J\u00e4ger und der Vertriebspartnerschaft mit Tchibo hat das Start-up die besten Voraussetzungen, um sich am Markt zu etablieren und die Expansion voranzutreiben.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201eWir sind bereit, Vollgas zu geben. Unsere Vision ist es, mit \u201aSUN Minimeal\u2018 einen neuen Standard f\u00fcr gesunde Ern\u00e4hrung im Alltag zu setzen\u201c, sagt Maike Grabher zuversichtlich. Erste Verkaufszahlen und Kundenfeedbacks werden in den kommenden Monaten zeigen, wie schnell sich das Produkt am Markt etablieren kann.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Die gesamte zweite Folge von \u201e2 Minuten 2 Millionen\u201c inklusive des Rekord-Deals steht auf der Streaming-Plattform JOYN zum Nachsehen bereit. Wer also die packende Verhandlungsrunde um das Millioneninvestment noch einmal erleben m\u00f6chte, kann dies jederzeit online tun.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Mit diesem historischen Investment hat \u201eSUN Minimeal\u201c einen starken Start hingelegt \u2013 und vielleicht ist das erst der Anfang einer Erfolgsgeschichte, die die \u00f6sterreichische Start-up-Welt nachhaltig ver\u00e4ndern wird.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Bild: PULS 4 \u00a9&nbsp;@ Gerry Frank Photography 2024<\/p>\n\n\n\n<ul class=\"wp-block-yoast-seo-related-links yoast-seo-related-links\">\n<li><a href=\"https:\/\/startupvalley.news\/de\/christian-jaeger-2min2mio\/\">Vom Schulabbrecher zum Selfmade-Million\u00e4r<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/startupvalley.news\/de\/edurino-ravensburger-edtech-startup-seriesb\/\">EDURINO: EdTech-Startup sichert sich \u20ac 17 Millionen in Series B<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/startupvalley.news\/de\/staffel-hoehle-der-loewen\/\">Rekord-Bieterei f\u00fcr Traum-Start-up!<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/startupvalley.news\/de\/die-hoehle-der-loewen-vox\/\">WER WIRD SCHNURREN, WER WIRD BR\u00dcLLEN?<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/startupvalley.news\/de\/hoehle-der-loewen-2\/\">Deal als Start in neue Sph\u00e4ren?<\/a><\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>Rekord Deal bei \u201e2 Minuten 2 Millionen\u201c: Start-up \u201eSUN Minimeal\u201c sichert sich Millionen-Investment<\/p>\n","protected":false},"author":9,"featured_media":112310,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[1],"tags":[15726,16337,470,586,22470],"class_list":["post-112307","post","type-post","status-publish","format-standard","has-post-thumbnail","category-startup-news","tag-deal","tag-expansion","tag-gesunde-ernaehrung","tag-investment","tag-start-up-show"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.8 (Yoast SEO v27.8) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Deal: Christian J\u00e4ger sichert sich Investition - StartupValley Magazine | Gr\u00fcnder, Startups &amp; Venture Capital<\/title>\n<meta name=\"description\" content=\"Erfahren Sie alles \u00fcber den spektakul\u00e4ren Deal in der neuen Staffel von 2 Minuten 2 Millionen und das Start-up SUN Minimeal.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/startupvalley.news\/de\/deal-sun-minimeal\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Spektakul\u00e4rer Deal bei 2 Minuten 2 Millionen\" \/>\n<meta property=\"og:description\" content=\"Erfahren Sie alles \u00fcber den spektakul\u00e4ren Deal in der neuen Staffel von 2 Minuten 2 Millionen und das Start-up SUN Minimeal.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/startupvalley.news\/de\/deal-sun-minimeal\/\" \/>\n<meta property=\"og:site_name\" content=\"StartupValley Magazine | Gr\u00fcnder, Startups &amp; Venture Capital\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/startupvalleynews\" \/>\n<meta property=\"article:published_time\" content=\"2025-03-01T08:57:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-09-30T06:33:18+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/startupvalley.news\/de\/wp-content\/uploads\/sites\/2\/2025\/02\/sun-minimeal_2min2mio12-c-puls-4_gerry-frank-36-Kopie.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"800\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"StartupValley\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@startup_valley\" \/>\n<meta name=\"twitter:site\" content=\"@startup_valley\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"StartupValley\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"5\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\\\/\\\/startupvalley.news\\\/de\\\/deal-sun-minimeal\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/startupvalley.news\\\/de\\\/deal-sun-minimeal\\\/\"},\"author\":{\"name\":\"StartupValley\",\"@id\":\"https:\\\/\\\/startupvalley.news\\\/de\\\/#\\\/schema\\\/person\\\/dc9abc71daa8d949d4f257f2e9883e00\"},\"headline\":\"Spektakul\u00e4rer Deal bei 2 Minuten 2 Millionen\",\"datePublished\":\"2025-03-01T08:57:00+00:00\",\"dateModified\":\"2025-09-30T06:33:18+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/startupvalley.news\\\/de\\\/deal-sun-minimeal\\\/\"},\"wordCount\":848,\"publisher\":{\"@id\":\"https:\\\/\\\/startupvalley.news\\\/de\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/startupvalley.news\\\/de\\\/deal-sun-minimeal\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/startupvalley.news\\\/de\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2025\\\/02\\\/sun-minimeal_2min2mio12-c-puls-4_gerry-frank-36-Kopie.jpg\",\"keywords\":[\"Deal\",\"Expansion\",\"gesunde Ern\u00e4hrung\",\"Investment\",\"Start-up-Show\"],\"articleSection\":[\"Startup News\"],\"inLanguage\":\"de\",\"copyrightYear\":\"2025\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/startupvalley.news\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/startupvalley.news\\\/de\\\/deal-sun-minimeal\\\/\",\"url\":\"https:\\\/\\\/startupvalley.news\\\/de\\\/deal-sun-minimeal\\\/\",\"name\":\"Deal: Christian J\u00e4ger sichert sich Investition - StartupValley Magazine | Gr\u00fcnder, Startups &amp; Venture Capital\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/startupvalley.news\\\/de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/startupvalley.news\\\/de\\\/deal-sun-minimeal\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/startupvalley.news\\\/de\\\/deal-sun-minimeal\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/startupvalley.news\\\/de\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2025\\\/02\\\/sun-minimeal_2min2mio12-c-puls-4_gerry-frank-36-Kopie.jpg\",\"datePublished\":\"2025-03-01T08:57:00+00:00\",\"dateModified\":\"2025-09-30T06:33:18+00:00\",\"description\":\"Erfahren Sie alles \u00fcber den spektakul\u00e4ren Deal in der neuen Staffel von 2 Minuten 2 Millionen und das Start-up SUN Minimeal.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/startupvalley.news\\\/de\\\/deal-sun-minimeal\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/startupvalley.news\\\/de\\\/deal-sun-minimeal\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/startupvalley.news\\\/de\\\/deal-sun-minimeal\\\/#primaryimage\",\"url\":\"https:\\\/\\\/startupvalley.news\\\/de\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2025\\\/02\\\/sun-minimeal_2min2mio12-c-puls-4_gerry-frank-36-Kopie.jpg\",\"contentUrl\":\"https:\\\/\\\/startupvalley.news\\\/de\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2025\\\/02\\\/sun-minimeal_2min2mio12-c-puls-4_gerry-frank-36-Kopie.jpg\",\"width\":1200,\"height\":800,\"caption\":\"deal SUN Minimeal Gr\u00fcnder mit Christian J\u00e4ger in 2 Minuten 2 Millionen @ puls-4 Fotograf Gerry Frank\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/startupvalley.news\\\/de\\\/deal-sun-minimeal\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/startupvalley.news\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Spektakul\u00e4rer Deal bei 2 Minuten 2 Millionen\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/startupvalley.news\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/startupvalley.news\\\/de\\\/\",\"name\":\"StartupValley\",\"description\":\"Magazin f\u00fcr Startups, Gr\u00fcnder und Funding\",\"publisher\":{\"@id\":\"https:\\\/\\\/startupvalley.news\\\/de\\\/#organization\"},\"alternateName\":\"StartupValley Magazin\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/startupvalley.news\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/startupvalley.news\\\/de\\\/#organization\",\"name\":\"StartupValley Media\",\"url\":\"https:\\\/\\\/startupvalley.news\\\/de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/startupvalley.news\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/startupvalley.news\\\/de\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2020\\\/12\\\/StartupValley-LOGO-neu-retina.png\",\"contentUrl\":\"https:\\\/\\\/startupvalley.news\\\/de\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2020\\\/12\\\/StartupValley-LOGO-neu-retina.png\",\"width\":460,\"height\":180,\"caption\":\"StartupValley Media\"},\"image\":{\"@id\":\"https:\\\/\\\/startupvalley.news\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/startupvalleynews\",\"https:\\\/\\\/x.com\\\/startup_valley\",\"https:\\\/\\\/www.twitch.tv\\\/startupvalley\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/startupvalleymagazine\",\"https:\\\/\\\/www.instagram.com\\\/startup_valley\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/startupvalley.news\\\/de\\\/#\\\/schema\\\/person\\\/dc9abc71daa8d949d4f257f2e9883e00\",\"name\":\"StartupValley\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6436ca57465a88bfa716825ebdd3bc23f850aaaa3a51d16da34504822452fa3a?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6436ca57465a88bfa716825ebdd3bc23f850aaaa3a51d16da34504822452fa3a?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6436ca57465a88bfa716825ebdd3bc23f850aaaa3a51d16da34504822452fa3a?s=96&d=mm&r=g\",\"caption\":\"StartupValley\"},\"description\":\"Das StartupValley Magazin ist Europas gro\u00dfes Magazin f\u00fcr Start-ups, Gr\u00fcnder und Entrepreneure. Ihr findet bei uns Tagesaktuelle News zu den neuesten Trends, Technologien und Gesch\u00e4ftsmodellen der internationalen Startup-Szene sowie Interviews mit erfolgreichen Gr\u00fcndern und Investoren.\",\"url\":\"https:\\\/\\\/startupvalley.news\\\/de\\\/author\\\/redaktion\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Deal: Christian J\u00e4ger sichert sich Investition - StartupValley Magazine | Gr\u00fcnder, Startups &amp; Venture Capital","description":"Erfahren Sie alles \u00fcber den spektakul\u00e4ren Deal in der neuen Staffel von 2 Minuten 2 Millionen und das Start-up SUN Minimeal.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/startupvalley.news\/de\/deal-sun-minimeal\/","og_locale":"de_DE","og_type":"article","og_title":"Spektakul\u00e4rer Deal bei 2 Minuten 2 Millionen","og_description":"Erfahren Sie alles \u00fcber den spektakul\u00e4ren Deal in der neuen Staffel von 2 Minuten 2 Millionen und das Start-up SUN Minimeal.","og_url":"https:\/\/startupvalley.news\/de\/deal-sun-minimeal\/","og_site_name":"StartupValley Magazine | Gr\u00fcnder, Startups &amp; Venture Capital","article_publisher":"https:\/\/www.facebook.com\/startupvalleynews","article_published_time":"2025-03-01T08:57:00+00:00","article_modified_time":"2025-09-30T06:33:18+00:00","og_image":[{"width":1200,"height":800,"url":"https:\/\/startupvalley.news\/de\/wp-content\/uploads\/sites\/2\/2025\/02\/sun-minimeal_2min2mio12-c-puls-4_gerry-frank-36-Kopie.jpg","type":"image\/jpeg"}],"author":"StartupValley","twitter_card":"summary_large_image","twitter_creator":"@startup_valley","twitter_site":"@startup_valley","twitter_misc":{"Verfasst von":"StartupValley","Gesch\u00e4tzte Lesezeit":"5\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/startupvalley.news\/de\/deal-sun-minimeal\/#article","isPartOf":{"@id":"https:\/\/startupvalley.news\/de\/deal-sun-minimeal\/"},"author":{"name":"StartupValley","@id":"https:\/\/startupvalley.news\/de\/#\/schema\/person\/dc9abc71daa8d949d4f257f2e9883e00"},"headline":"Spektakul\u00e4rer Deal bei 2 Minuten 2 Millionen","datePublished":"2025-03-01T08:57:00+00:00","dateModified":"2025-09-30T06:33:18+00:00","mainEntityOfPage":{"@id":"https:\/\/startupvalley.news\/de\/deal-sun-minimeal\/"},"wordCount":848,"publisher":{"@id":"https:\/\/startupvalley.news\/de\/#organization"},"image":{"@id":"https:\/\/startupvalley.news\/de\/deal-sun-minimeal\/#primaryimage"},"thumbnailUrl":"https:\/\/startupvalley.news\/de\/wp-content\/uploads\/sites\/2\/2025\/02\/sun-minimeal_2min2mio12-c-puls-4_gerry-frank-36-Kopie.jpg","keywords":["Deal","Expansion","gesunde Ern\u00e4hrung","Investment","Start-up-Show"],"articleSection":["Startup News"],"inLanguage":"de","copyrightYear":"2025","copyrightHolder":{"@id":"https:\/\/startupvalley.news\/#organization"}},{"@type":"WebPage","@id":"https:\/\/startupvalley.news\/de\/deal-sun-minimeal\/","url":"https:\/\/startupvalley.news\/de\/deal-sun-minimeal\/","name":"Deal: Christian J\u00e4ger sichert sich Investition - StartupValley Magazine | Gr\u00fcnder, Startups &amp; Venture Capital","isPartOf":{"@id":"https:\/\/startupvalley.news\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/startupvalley.news\/de\/deal-sun-minimeal\/#primaryimage"},"image":{"@id":"https:\/\/startupvalley.news\/de\/deal-sun-minimeal\/#primaryimage"},"thumbnailUrl":"https:\/\/startupvalley.news\/de\/wp-content\/uploads\/sites\/2\/2025\/02\/sun-minimeal_2min2mio12-c-puls-4_gerry-frank-36-Kopie.jpg","datePublished":"2025-03-01T08:57:00+00:00","dateModified":"2025-09-30T06:33:18+00:00","description":"Erfahren Sie alles \u00fcber den spektakul\u00e4ren Deal in der neuen Staffel von 2 Minuten 2 Millionen und das Start-up SUN Minimeal.","breadcrumb":{"@id":"https:\/\/startupvalley.news\/de\/deal-sun-minimeal\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/startupvalley.news\/de\/deal-sun-minimeal\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/startupvalley.news\/de\/deal-sun-minimeal\/#primaryimage","url":"https:\/\/startupvalley.news\/de\/wp-content\/uploads\/sites\/2\/2025\/02\/sun-minimeal_2min2mio12-c-puls-4_gerry-frank-36-Kopie.jpg","contentUrl":"https:\/\/startupvalley.news\/de\/wp-content\/uploads\/sites\/2\/2025\/02\/sun-minimeal_2min2mio12-c-puls-4_gerry-frank-36-Kopie.jpg","width":1200,"height":800,"caption":"deal SUN Minimeal Gr\u00fcnder mit Christian J\u00e4ger in 2 Minuten 2 Millionen @ puls-4 Fotograf Gerry Frank"},{"@type":"BreadcrumbList","@id":"https:\/\/startupvalley.news\/de\/deal-sun-minimeal\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/startupvalley.news\/de\/"},{"@type":"ListItem","position":2,"name":"Spektakul\u00e4rer Deal bei 2 Minuten 2 Millionen"}]},{"@type":"WebSite","@id":"https:\/\/startupvalley.news\/de\/#website","url":"https:\/\/startupvalley.news\/de\/","name":"StartupValley","description":"Magazin f\u00fcr Startups, Gr\u00fcnder und Funding","publisher":{"@id":"https:\/\/startupvalley.news\/de\/#organization"},"alternateName":"StartupValley Magazin","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/startupvalley.news\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/startupvalley.news\/de\/#organization","name":"StartupValley Media","url":"https:\/\/startupvalley.news\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/startupvalley.news\/de\/#\/schema\/logo\/image\/","url":"https:\/\/startupvalley.news\/de\/wp-content\/uploads\/sites\/2\/2020\/12\/StartupValley-LOGO-neu-retina.png","contentUrl":"https:\/\/startupvalley.news\/de\/wp-content\/uploads\/sites\/2\/2020\/12\/StartupValley-LOGO-neu-retina.png","width":460,"height":180,"caption":"StartupValley Media"},"image":{"@id":"https:\/\/startupvalley.news\/de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/startupvalleynews","https:\/\/x.com\/startup_valley","https:\/\/www.twitch.tv\/startupvalley","https:\/\/www.linkedin.com\/company\/startupvalleymagazine","https:\/\/www.instagram.com\/startup_valley"]},{"@type":"Person","@id":"https:\/\/startupvalley.news\/de\/#\/schema\/person\/dc9abc71daa8d949d4f257f2e9883e00","name":"StartupValley","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/6436ca57465a88bfa716825ebdd3bc23f850aaaa3a51d16da34504822452fa3a?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/6436ca57465a88bfa716825ebdd3bc23f850aaaa3a51d16da34504822452fa3a?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/6436ca57465a88bfa716825ebdd3bc23f850aaaa3a51d16da34504822452fa3a?s=96&d=mm&r=g","caption":"StartupValley"},"description":"Das StartupValley Magazin ist Europas gro\u00dfes Magazin f\u00fcr Start-ups, Gr\u00fcnder und Entrepreneure. Ihr findet bei uns Tagesaktuelle News zu den neuesten Trends, Technologien und Gesch\u00e4ftsmodellen der internationalen Startup-Szene sowie Interviews mit erfolgreichen Gr\u00fcndern und Investoren.","url":"https:\/\/startupvalley.news\/de\/author\/redaktion\/"}]}},"_links":{"self":[{"href":"https:\/\/startupvalley.news\/de\/wp-json\/wp\/v2\/posts\/112307","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/startupvalley.news\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/startupvalley.news\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/startupvalley.news\/de\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/startupvalley.news\/de\/wp-json\/wp\/v2\/comments?post=112307"}],"version-history":[{"count":3,"href":"https:\/\/startupvalley.news\/de\/wp-json\/wp\/v2\/posts\/112307\/revisions"}],"predecessor-version":[{"id":117418,"href":"https:\/\/startupvalley.news\/de\/wp-json\/wp\/v2\/posts\/112307\/revisions\/117418"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/startupvalley.news\/de\/wp-json\/wp\/v2\/media\/112310"}],"wp:attachment":[{"href":"https:\/\/startupvalley.news\/de\/wp-json\/wp\/v2\/media?parent=112307"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/startupvalley.news\/de\/wp-json\/wp\/v2\/categories?post=112307"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/startupvalley.news\/de\/wp-json\/wp\/v2\/tags?post=112307"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}