{"id":118940,"date":"2025-12-12T08:27:37","date_gmt":"2025-12-12T07:27:37","guid":{"rendered":"https:\/\/startupvalley.news\/de\/?p=118940"},"modified":"2026-06-10T08:01:36","modified_gmt":"2026-06-10T06:01:36","slug":"microharvest-verbindet-human-und-food","status":"publish","type":"post","link":"https:\/\/startupvalley.news\/de\/microharvest-verbindet-human-und-food\/","title":{"rendered":"Wie k\u00f6nnen wir Protein erzeugen, ohne von Ressourcen und Grenzen abh\u00e4ngig zu sein?"},"content":{"rendered":"\n<h2 class=\"wp-block-heading\" id=\"h-microharvest-produziert-nachhaltiges-mikrobielles-protein-durch-fermentation-und-eroffnet-damit-neue-wege-fur-eine-zukunftsfahige-ernahrung\">MicroHarvest produziert nachhaltiges, mikrobielles Protein durch Fermentation und er\u00f6ffnet damit neue Wege f\u00fcr eine zukunftsf\u00e4hige Ern\u00e4hrung<\/h2>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-wie-wurden-sie-microharvest-und-das-team-dahinter-vorstellen\">Wie w\u00fcrden Sie MicroHarvest und das Team dahinter vorstellen?<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">MicroHarvest ist ein Biotech-Unternehmen, das mithilfe nat\u00fcrlicher Fermentation mikrobielles Protein herstellt. Extrem schnell, skalierbar und ressourcenschonend. Aber ganz ehrlich: Das Team ist wirklich besonders bei MicroHarvest. Wir haben Expertinnen und Experten aus Biotechnologie, Prozessengineering, Operations, Produkt und Business zusammengebracht, die in ihren jeweiligen Feldern teilweise zur absoluten Weltspitze geh\u00f6ren und die sich bewusst entschieden haben, gemeinsam an einer Sache zu arbeiten.<br>Diese Mischung aus wissenschaftlicher Tiefe und industrieller Umsetzungsst\u00e4rke sp\u00fcrt man jeden Tag: Wir sind nicht nur begeistert von der Technologie, sondern vor allem davon, was wir damit m\u00f6glich machen k\u00f6nnen. Uns treibt die gemeinsame Mission an, \u201eBetter Protein\u201c ohne Kompromisse zu liefern und damit einen echten Beitrag zu einem zukunftsf\u00e4higen Ern\u00e4hrungssystem zu leisten.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-welche-vision-verfolgt-microharvest\">Welche Vision verfolgt MicroHarvest?<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Wir bei MicroHarvest verfolgen ein klares Ziel: nat\u00fcrliches, n\u00e4hrstoffreiches Protein f\u00fcr m\u00f6glichst viele Menschen und Tiere zug\u00e4nglich zu machen. Ohne Tierhaltung und ohne knappe Anbaufl\u00e4chen, und gleichzeitig ohne Abstriche bei Qualit\u00e4t und Nachhaltigkeit. Unser Ziel ist ein Ern\u00e4hrungssystem, das ges\u00fcndere Ern\u00e4hrung f\u00fcr einen ges\u00fcnderen Planeten m\u00f6glich macht und die wachsende globale Proteinl\u00fccke verl\u00e4sslich schlie\u00dft.<br>Daf\u00fcr nutzen wir Mikroorganismen als \u201eProtein-Fabriken\u201c und bauen ein Produktionssystem, das unabh\u00e4ngig von Klima, Boden und Jahreszeiten ganzj\u00e4hrig laufen kann. So machen wir hochwertige Proteine deutlich verl\u00e4sslicher verf\u00fcgbar und reduzieren gleichzeitig den Ressourcenverbrauch entlang der gesamten Wertsch\u00f6pfung.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-fur-welche-zielgruppen-entwickeln-sie-ihre-proteinlosungen\">F\u00fcr welche Zielgruppen entwickeln Sie Ihre Proteinl\u00f6sungen?<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Wir streben den Einstieg in Human Food an, sind jedoch bereits heute mit unseren Produkten im Petfood- und Aquafeed-Bereich am Markt. Diese Segmente weisen einen besonders hohen Bedarf an stabilen, hochwertigen und nachhaltigeren Proteinen auf. Im Petfood z\u00e4hlen vor allem Geschmackhaftigkeit, gleichbleibende Qualit\u00e4t, hypoallergene\/Clean-Label-Optionen und eine verl\u00e4ssliche Lieferkette.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-wie-gelingt-es-ihnen-proteine-in-24-stunden-zu-produzieren\">Wie gelingt es Ihnen, Proteine in 24 Stunden zu produzieren?<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Unsere Geschwindigkeit kommt nicht nur daher, dass Mikroorganismen \u201evon Natur aus\u201c schnell wachsen. Sie ist vor allem das Ergebnis unserer eigens entwickelten MicroHarvest-Technologie und Prozessf\u00fchrung. Wir haben einen Fermentationsprozess aufgebaut, der in Bioreaktoren optimale Bedingungen schafft und so aus landwirtschaftlichen Nebenstr\u00f6men in sehr kurzer Zeit proteinreiche Biomasse erzeugt \u2013 vom Rohstoff bis zum Endprodukt in nur 24 Stunden. Der Vorteil: extrem kurze Produktionszyklen, hohe Planbarkeit, schnelle Skalierung und konstante Produktqualit\u00e4t, besonders attraktiv f\u00fcr industrielle Anwender mit hohen Anforderungen an Zuverl\u00e4ssigkeit und Spezifikationen.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-was-unterscheidet-ihre-fermentationsbasierte-herstellung-von-konventionellen-methoden\">Was unterscheidet Ihre fermentationsbasierte Herstellung von konventionellen Methoden?<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Fermentation ist ein bew\u00e4hrtes Prinzip (wie bei Bier oder Joghurt). Wir setzen es modern und industriell effizient ein. Im Unterschied zu tierischer und vieler pflanzlicher Produktion ist unser Prozess nicht abh\u00e4ngig von Ackerfl\u00e4chen, Wetter und Saison, sondern l\u00e4uft kontrolliert und 24\/7. Dadurch kombinieren wir Skalierbarkeit mit Ressourceneffizienz (u. a. deutlich weniger Fl\u00e4chen- und Wasserbedarf sowie sehr niedrige Emissionen im Vergleich zu konventionellen Proteinen).<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-welche-herausforderungen-begegnen-ihnen-aktuell\">Welche Herausforderungen begegnen Ihnen aktuell?<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Aktuell ist die gr\u00f6\u00dfte Herausforderung ganz klar die Regulatorik, insbesondere mit Blick auf den Lebensmittelsektor. Gleichzeitig bewegt sich hier sp\u00fcrbar etwas: Biotechnologie und Biomanufacturing gewinnen in Europa politisch und wirtschaftlich an Bedeutung, und es gibt R\u00fcckenwind, Genehmigungs- und Innovationsprozesse perspektivisch besser zu unterst\u00fctzen.<br>Die zweite zentrale Herausforderung ist der Schritt von der Entwicklung zur produzierenden industriellen Realit\u00e4t. Genau daran arbeiten wir konsequent \u2013 und wir konnten bereits zeigen, dass es funktioniert: Mit unserer Pilotanlage in Lissabon und zusammen mit einem Partner haben wir den \u00dcbergang vom Labor zur industriellen Fertigung erfolgreich hinbekommen. Das ist f\u00fcr uns ein wichtiger Beweis, dass unsere Technologie nicht nur im kleinen Ma\u00dfstab \u00fcberzeugt, sondern skalierbar ist.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-welche-rolle-spielen-nachhaltigkeit-und-ressourceneffizienz-fur-ihr-geschaftsmodell\">Welche Rolle spielen Nachhaltigkeit und Ressourceneffizienz f\u00fcr Ihr Gesch\u00e4ftsmodell?<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Nachhaltigkeit ist bei uns kein \u201eAdd-on\u201c, sondern Kern des Gesch\u00e4ftsmodells: Wirkung entsteht nur, wenn eine L\u00f6sung im gro\u00dfen Ma\u00dfstab funktioniert. Deshalb denken wir Nachhaltigkeit immer zusammen mit Skalierung und Wirtschaftlichkeit: kurze Prozesszeiten, geringer Ressourcenbedarf und robuste, wiederholbare Produktion sind entscheidend, um Akzeptanz im Markt zu gewinnen und langfristig konkurrenzf\u00e4hig zu sein.<br>Ein wichtiger Hebel dabei ist unser Rohstoffansatz: Wir nutzen landwirtschaftliche Nebenstr\u00f6me und denken Proteinproduktion damit auch als Upcycling \u2013 aus bestehenden Agrarstr\u00f6men wird hochwertiges, n\u00e4hrstoffreiches Protein. Gleichzeitig setzen wir auf lokale Beschaffung und lokale Produktion: Wir wollen Lieferketten bewusst regional halten, Transportwege reduzieren und Resilienz aufbauen, in Europa und perspektivisch auch mit Produktionsstandorten auf anderen Kontinenten. So entsteht Nachhaltigkeit nicht nur auf Produktebene, sondern strukturell entlang der gesamten Wertsch\u00f6pfung.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-wie-verandert-die-pilotanlage-in-lissabon-ihre-nachsten-schritte\">Wie ver\u00e4ndert die Pilotanlage in Lissabon Ihre n\u00e4chsten Schritte?<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Die Pilotanlage war ein wichtiger Schritt, um unsere Technologie im industriellen Kontext weiter zu validieren: Prozessstabilit\u00e4t, Produkt- und Kundenvalidierung sowie Datengrundlage f\u00fcr den n\u00e4chsten Scale-up. Auf dieser Basis arbeiten wir an der n\u00e4chsten Ausbaustufe: eine gro\u00dfe Produktion, die 15.000 Tonnen im Jahr produzieren wird.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-welche-anwendungen-ihrer-proteine-sind-besonders-vielversprechend\">Welche Anwendungen Ihrer Proteine sind besonders vielversprechend?<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Kurzfristig sehen wir die st\u00e4rksten Anwendungen in Petfood (z. B. Leckerlis\/erg\u00e4nzende Produkte, oder auch vollst\u00e4ndige Rationen) sowie in Aquafeed als nachhaltigere Alternative zu klassischen Proteinquellen. Langfristig liegt das gr\u00f6\u00dfte Potenzial im Human-Food-Segment, weil dort die globale Proteinl\u00fccke am st\u00e4rksten sp\u00fcrbar wird \u2013 und Fermentation eine skalierbare Antwort liefern kann.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-wie-sichern-sie-die-produktqualitat\">Wie sichern Sie die Produktqualit\u00e4t?<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Wir sichern Qualit\u00e4t vor allem \u00fcber kontrollierte Prozesse und konsequente Qualit\u00e4tskontrollen. Dazu kommen Produktmerkmale wie hoher Proteingehalt, gute Aminos\u00e4ure-Verf\u00fcgbarkeit\/Verdaulichkeit und guter Geschmack. Ziel ist: nachhaltiger Impact ohne Abstriche bei Performance und Konsistenz.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-drei-ratschlage-fur-grunderinnen-und-grunder\">Drei Ratschl\u00e4ge f\u00fcr Gr\u00fcnderinnen und Gr\u00fcnder?<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Gro\u00df denken \u2013 mit echtem Purpose: L\u00f6st ein reales, relevantes Problem. Ein starkes Warum schafft Orientierung, Qualit\u00e4t und Wirkung.<br>Fokussiere dich \u2013 statt allen gefallen zu wollen: Versucht nicht, jede Erwartung zu erf\u00fcllen oder alles gleichzeitig zu machen. Trefft Entscheidungen nach dem, was wirklich z\u00e4hlt \u2013 Fokus schl\u00e4gt Harmonie.<br>F\u00fcr morgen einstellen \u2013 und bewusst schlank bleiben: Nur Menschen einstellen, f\u00fcr die ihr selbst gerne arbeiten w\u00fcrdet \u2013 besonders in F\u00fchrungsrollen. Wenige sehr gute Mitarbeitende schlagen viele Mittelm\u00e4\u00dfige.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-wohin-entwickelt-sich-microharvest-in-den-nachsten-jahren\">Wohin entwickelt sich MicroHarvest in den n\u00e4chsten Jahren?<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">In den n\u00e4chsten Jahren bauen wir MicroHarvest von der validierten industriellen Technologie zur gro\u00dfskaligen, industriellen Produktion aus. Entscheidende Meilensteine sind: Ausbau der Produktionskapazit\u00e4ten (~15.000 Tonnen\/Jahr als n\u00e4chste gro\u00dfe Stufe), st\u00e4rkere Marktdurchdringung in Petfood und Aquafeed und Eintritt in den Human-Food-Markt.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Bild Jonathan Roberz Bildcredits MicroHarvest<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Wir bedanken uns bei <a href=\"https:\/\/www.linkedin.com\/in\/roberz\/\" target=\"_blank\" rel=\"noreferrer noopener\">Jonathan Roberz<\/a>\u00a0f\u00fcr das Interview<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Aussagen des Autors und des Interviewpartners geben nicht unbedingt die Meinung der Redaktion und des Verlags wieder.<\/p>\n\n\n\n<ul class=\"wp-block-yoast-seo-related-links yoast-seo-related-links\">\n<li><a href=\"https:\/\/startupvalley.news\/de\/human-ai-ethische-ki-und-vertrauenswuerdige-technologie\/\">Human AI \u2013 wie Startups k\u00fcnstliche Intelligenz menschlicher machen<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/startupvalley.news\/de\/dear-human-personal-und-diversityberatung\/\">Sei bereit, Risiken einzugehen und lerne mit R\u00fcckschl\u00e4gen umzugehen<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/startupvalley.news\/de\/win-win-for-work\/\">Lernt Eure gr\u00f6\u00dften Kritiker:innen zu lieben<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/startupvalley.news\/de\/crcl-circle-management\/\">Du kannst nur gewinnen<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/startupvalley.news\/de\/better-nature-tempeh-protein\/\">Ist das die Zukunft unseres t\u00e4glichen Proteins?<\/a><\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>MicroHarvest zeigt, wie mikrobielles Protein neue M\u00f6glichkeiten f\u00fcr ein nachhaltiges Ern\u00e4hrungssystem schafft. Die schnelle, skalierbare Fermentation er\u00f6ffnet L\u00f6sungen f\u00fcr Mensch, Tier und Umwelt.<\/p>\n","protected":false},"author":9,"featured_media":118941,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[26473],"tags":[25898,5681,6040,9033,183,5656,13,12800],"class_list":["post-118940","post","type-post","status-publish","format-standard","has-post-thumbnail","category-interviews","tag-fermentation","tag-food","tag-nachhaltigkeit","tag-produktion","tag-protein","tag-qualitaet","tag-ressourcen","tag-skalierung"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.3 (Yoast SEO v28.3) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>MicroHarvest verbindet Human und Food f\u00fcr neue L\u00f6sungen<\/title>\n<meta name=\"description\" content=\"MicroHarvest entwickelt Protein durch Fermentation und schafft L\u00f6sungen, die Human und Food nachhaltig verbinden.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/startupvalley.news\/de\/microharvest-verbindet-human-und-food\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Wie k\u00f6nnen wir Protein erzeugen, ohne von Ressourcen und Grenzen abh\u00e4ngig zu sein?\" \/>\n<meta property=\"og:description\" content=\"MicroHarvest entwickelt Protein durch Fermentation und schafft L\u00f6sungen, die Human und Food nachhaltig verbinden.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/startupvalley.news\/de\/microharvest-verbindet-human-und-food\/\" \/>\n<meta property=\"og:site_name\" content=\"StartupValley\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/startupvalleynews\" \/>\n<meta property=\"article:published_time\" content=\"2025-12-12T07:27:37+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-06-10T06:01:36+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/startupvalley.news\/de\/wp-content\/uploads\/sites\/2\/2025\/12\/MicroHarvest_COB1920.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"969\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"StartupValley\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@startup_valley\" \/>\n<meta name=\"twitter:site\" content=\"@startup_valley\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"StartupValley\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"6\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\\\/\\\/startupvalley.news\\\/de\\\/microharvest-verbindet-human-und-food\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/startupvalley.news\\\/de\\\/microharvest-verbindet-human-und-food\\\/\"},\"author\":{\"name\":\"StartupValley\",\"@id\":\"https:\\\/\\\/startupvalley.news\\\/de\\\/#\\\/schema\\\/person\\\/dc9abc71daa8d949d4f257f2e9883e00\"},\"headline\":\"Wie k\u00f6nnen wir Protein erzeugen, ohne von Ressourcen und Grenzen abh\u00e4ngig zu sein?\",\"datePublished\":\"2025-12-12T07:27:37+00:00\",\"dateModified\":\"2026-06-10T06:01:36+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/startupvalley.news\\\/de\\\/microharvest-verbindet-human-und-food\\\/\"},\"wordCount\":1160,\"publisher\":{\"@id\":\"https:\\\/\\\/startupvalley.news\\\/de\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/startupvalley.news\\\/de\\\/microharvest-verbindet-human-und-food\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/startupvalley.news\\\/de\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2025\\\/12\\\/MicroHarvest_COB1920.jpg\",\"keywords\":[\"Fermentation\",\"Food\",\"Nachhaltigkeit\",\"produktion\",\"Protein\",\"Qualit\u00e4t\",\"Ressourcen\",\"Skalierung\"],\"articleSection\":[\"Interviews\"],\"inLanguage\":\"de\",\"copyrightYear\":\"2025\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/startupvalley.news\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/startupvalley.news\\\/de\\\/microharvest-verbindet-human-und-food\\\/\",\"url\":\"https:\\\/\\\/startupvalley.news\\\/de\\\/microharvest-verbindet-human-und-food\\\/\",\"name\":\"MicroHarvest verbindet Human und Food f\u00fcr neue L\u00f6sungen\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/startupvalley.news\\\/de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/startupvalley.news\\\/de\\\/microharvest-verbindet-human-und-food\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/startupvalley.news\\\/de\\\/microharvest-verbindet-human-und-food\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/startupvalley.news\\\/de\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2025\\\/12\\\/MicroHarvest_COB1920.jpg\",\"datePublished\":\"2025-12-12T07:27:37+00:00\",\"dateModified\":\"2026-06-10T06:01:36+00:00\",\"description\":\"MicroHarvest entwickelt Protein durch Fermentation und schafft L\u00f6sungen, die Human und Food nachhaltig verbinden.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/startupvalley.news\\\/de\\\/microharvest-verbindet-human-und-food\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/startupvalley.news\\\/de\\\/microharvest-verbindet-human-und-food\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/startupvalley.news\\\/de\\\/microharvest-verbindet-human-und-food\\\/#primaryimage\",\"url\":\"https:\\\/\\\/startupvalley.news\\\/de\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2025\\\/12\\\/MicroHarvest_COB1920.jpg\",\"contentUrl\":\"https:\\\/\\\/startupvalley.news\\\/de\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2025\\\/12\\\/MicroHarvest_COB1920.jpg\",\"width\":1200,\"height\":969,\"caption\":\"MicroHarvest verbindet Human und Food f\u00fcr neue L\u00f6sungen Bild Jonathan Roberz Bildcredits MicroHarvest\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/startupvalley.news\\\/de\\\/microharvest-verbindet-human-und-food\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/startupvalley.news\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Wie k\u00f6nnen wir Protein erzeugen, ohne von Ressourcen und Grenzen abh\u00e4ngig zu sein?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/startupvalley.news\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/startupvalley.news\\\/de\\\/\",\"name\":\"StartupValley\",\"description\":\"Startup-News, Funding &amp; Gr\u00fcnder-Interviews\",\"publisher\":{\"@id\":\"https:\\\/\\\/startupvalley.news\\\/de\\\/#organization\"},\"alternateName\":\"StartupValley Magazin\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/startupvalley.news\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/startupvalley.news\\\/de\\\/#organization\",\"name\":\"StartupValley Media\",\"url\":\"https:\\\/\\\/startupvalley.news\\\/de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/startupvalley.news\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/startupvalley.news\\\/de\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2020\\\/12\\\/StartupValley-LOGO-neu-retina.png\",\"contentUrl\":\"https:\\\/\\\/startupvalley.news\\\/de\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2020\\\/12\\\/StartupValley-LOGO-neu-retina.png\",\"width\":460,\"height\":180,\"caption\":\"StartupValley Media\"},\"image\":{\"@id\":\"https:\\\/\\\/startupvalley.news\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/startupvalleynews\",\"https:\\\/\\\/x.com\\\/startup_valley\",\"https:\\\/\\\/www.twitch.tv\\\/startupvalley\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/startupvalleymagazine\",\"https:\\\/\\\/www.instagram.com\\\/startup_valley\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/startupvalley.news\\\/de\\\/#\\\/schema\\\/person\\\/dc9abc71daa8d949d4f257f2e9883e00\",\"name\":\"StartupValley\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6436ca57465a88bfa716825ebdd3bc23f850aaaa3a51d16da34504822452fa3a?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6436ca57465a88bfa716825ebdd3bc23f850aaaa3a51d16da34504822452fa3a?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6436ca57465a88bfa716825ebdd3bc23f850aaaa3a51d16da34504822452fa3a?s=96&d=mm&r=g\",\"caption\":\"StartupValley\"},\"description\":\"Das StartupValley Magazin ist Europas gro\u00dfes Magazin f\u00fcr Start-ups, Gr\u00fcnder und Entrepreneure. Ihr findet bei uns Tagesaktuelle News zu den neuesten Trends, Technologien und Gesch\u00e4ftsmodellen der internationalen Startup-Szene sowie Interviews mit erfolgreichen Gr\u00fcndern und Investoren.\",\"url\":\"https:\\\/\\\/startupvalley.news\\\/de\\\/author\\\/redaktion\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"MicroHarvest verbindet Human und Food f\u00fcr neue L\u00f6sungen","description":"MicroHarvest entwickelt Protein durch Fermentation und schafft L\u00f6sungen, die Human und Food nachhaltig verbinden.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/startupvalley.news\/de\/microharvest-verbindet-human-und-food\/","og_locale":"de_DE","og_type":"article","og_title":"Wie k\u00f6nnen wir Protein erzeugen, ohne von Ressourcen und Grenzen abh\u00e4ngig zu sein?","og_description":"MicroHarvest entwickelt Protein durch Fermentation und schafft L\u00f6sungen, die Human und Food nachhaltig verbinden.","og_url":"https:\/\/startupvalley.news\/de\/microharvest-verbindet-human-und-food\/","og_site_name":"StartupValley","article_publisher":"https:\/\/www.facebook.com\/startupvalleynews","article_published_time":"2025-12-12T07:27:37+00:00","article_modified_time":"2026-06-10T06:01:36+00:00","og_image":[{"width":1200,"height":969,"url":"https:\/\/startupvalley.news\/de\/wp-content\/uploads\/sites\/2\/2025\/12\/MicroHarvest_COB1920.jpg","type":"image\/jpeg"}],"author":"StartupValley","twitter_card":"summary_large_image","twitter_creator":"@startup_valley","twitter_site":"@startup_valley","twitter_misc":{"Verfasst von":"StartupValley","Gesch\u00e4tzte Lesezeit":"6\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/startupvalley.news\/de\/microharvest-verbindet-human-und-food\/#article","isPartOf":{"@id":"https:\/\/startupvalley.news\/de\/microharvest-verbindet-human-und-food\/"},"author":{"name":"StartupValley","@id":"https:\/\/startupvalley.news\/de\/#\/schema\/person\/dc9abc71daa8d949d4f257f2e9883e00"},"headline":"Wie k\u00f6nnen wir Protein erzeugen, ohne von Ressourcen und Grenzen abh\u00e4ngig zu sein?","datePublished":"2025-12-12T07:27:37+00:00","dateModified":"2026-06-10T06:01:36+00:00","mainEntityOfPage":{"@id":"https:\/\/startupvalley.news\/de\/microharvest-verbindet-human-und-food\/"},"wordCount":1160,"publisher":{"@id":"https:\/\/startupvalley.news\/de\/#organization"},"image":{"@id":"https:\/\/startupvalley.news\/de\/microharvest-verbindet-human-und-food\/#primaryimage"},"thumbnailUrl":"https:\/\/startupvalley.news\/de\/wp-content\/uploads\/sites\/2\/2025\/12\/MicroHarvest_COB1920.jpg","keywords":["Fermentation","Food","Nachhaltigkeit","produktion","Protein","Qualit\u00e4t","Ressourcen","Skalierung"],"articleSection":["Interviews"],"inLanguage":"de","copyrightYear":"2025","copyrightHolder":{"@id":"https:\/\/startupvalley.news\/#organization"}},{"@type":"WebPage","@id":"https:\/\/startupvalley.news\/de\/microharvest-verbindet-human-und-food\/","url":"https:\/\/startupvalley.news\/de\/microharvest-verbindet-human-und-food\/","name":"MicroHarvest verbindet Human und Food f\u00fcr neue L\u00f6sungen","isPartOf":{"@id":"https:\/\/startupvalley.news\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/startupvalley.news\/de\/microharvest-verbindet-human-und-food\/#primaryimage"},"image":{"@id":"https:\/\/startupvalley.news\/de\/microharvest-verbindet-human-und-food\/#primaryimage"},"thumbnailUrl":"https:\/\/startupvalley.news\/de\/wp-content\/uploads\/sites\/2\/2025\/12\/MicroHarvest_COB1920.jpg","datePublished":"2025-12-12T07:27:37+00:00","dateModified":"2026-06-10T06:01:36+00:00","description":"MicroHarvest entwickelt Protein durch Fermentation und schafft L\u00f6sungen, die Human und Food nachhaltig verbinden.","breadcrumb":{"@id":"https:\/\/startupvalley.news\/de\/microharvest-verbindet-human-und-food\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/startupvalley.news\/de\/microharvest-verbindet-human-und-food\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/startupvalley.news\/de\/microharvest-verbindet-human-und-food\/#primaryimage","url":"https:\/\/startupvalley.news\/de\/wp-content\/uploads\/sites\/2\/2025\/12\/MicroHarvest_COB1920.jpg","contentUrl":"https:\/\/startupvalley.news\/de\/wp-content\/uploads\/sites\/2\/2025\/12\/MicroHarvest_COB1920.jpg","width":1200,"height":969,"caption":"MicroHarvest verbindet Human und Food f\u00fcr neue L\u00f6sungen Bild Jonathan Roberz Bildcredits MicroHarvest"},{"@type":"BreadcrumbList","@id":"https:\/\/startupvalley.news\/de\/microharvest-verbindet-human-und-food\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/startupvalley.news\/de\/"},{"@type":"ListItem","position":2,"name":"Wie k\u00f6nnen wir Protein erzeugen, ohne von Ressourcen und Grenzen abh\u00e4ngig zu sein?"}]},{"@type":"WebSite","@id":"https:\/\/startupvalley.news\/de\/#website","url":"https:\/\/startupvalley.news\/de\/","name":"StartupValley","description":"Startup-News, Funding &amp; Gr\u00fcnder-Interviews","publisher":{"@id":"https:\/\/startupvalley.news\/de\/#organization"},"alternateName":"StartupValley Magazin","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/startupvalley.news\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/startupvalley.news\/de\/#organization","name":"StartupValley Media","url":"https:\/\/startupvalley.news\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/startupvalley.news\/de\/#\/schema\/logo\/image\/","url":"https:\/\/startupvalley.news\/de\/wp-content\/uploads\/sites\/2\/2020\/12\/StartupValley-LOGO-neu-retina.png","contentUrl":"https:\/\/startupvalley.news\/de\/wp-content\/uploads\/sites\/2\/2020\/12\/StartupValley-LOGO-neu-retina.png","width":460,"height":180,"caption":"StartupValley Media"},"image":{"@id":"https:\/\/startupvalley.news\/de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/startupvalleynews","https:\/\/x.com\/startup_valley","https:\/\/www.twitch.tv\/startupvalley","https:\/\/www.linkedin.com\/company\/startupvalleymagazine","https:\/\/www.instagram.com\/startup_valley"]},{"@type":"Person","@id":"https:\/\/startupvalley.news\/de\/#\/schema\/person\/dc9abc71daa8d949d4f257f2e9883e00","name":"StartupValley","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/6436ca57465a88bfa716825ebdd3bc23f850aaaa3a51d16da34504822452fa3a?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/6436ca57465a88bfa716825ebdd3bc23f850aaaa3a51d16da34504822452fa3a?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/6436ca57465a88bfa716825ebdd3bc23f850aaaa3a51d16da34504822452fa3a?s=96&d=mm&r=g","caption":"StartupValley"},"description":"Das StartupValley Magazin ist Europas gro\u00dfes Magazin f\u00fcr Start-ups, Gr\u00fcnder und Entrepreneure. Ihr findet bei uns Tagesaktuelle News zu den neuesten Trends, Technologien und Gesch\u00e4ftsmodellen der internationalen Startup-Szene sowie Interviews mit erfolgreichen Gr\u00fcndern und Investoren.","url":"https:\/\/startupvalley.news\/de\/author\/redaktion\/"}]}},"_links":{"self":[{"href":"https:\/\/startupvalley.news\/de\/wp-json\/wp\/v2\/posts\/118940","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/startupvalley.news\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/startupvalley.news\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/startupvalley.news\/de\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/startupvalley.news\/de\/wp-json\/wp\/v2\/comments?post=118940"}],"version-history":[{"count":1,"href":"https:\/\/startupvalley.news\/de\/wp-json\/wp\/v2\/posts\/118940\/revisions"}],"predecessor-version":[{"id":118942,"href":"https:\/\/startupvalley.news\/de\/wp-json\/wp\/v2\/posts\/118940\/revisions\/118942"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/startupvalley.news\/de\/wp-json\/wp\/v2\/media\/118941"}],"wp:attachment":[{"href":"https:\/\/startupvalley.news\/de\/wp-json\/wp\/v2\/media?parent=118940"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/startupvalley.news\/de\/wp-json\/wp\/v2\/categories?post=118940"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/startupvalley.news\/de\/wp-json\/wp\/v2\/tags?post=118940"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}