{"id":73014,"date":"2020-10-19T00:01:55","date_gmt":"2020-10-18T22:01:55","guid":{"rendered":"https:\/\/www.startupvalley.news\/de\/?p=73014"},"modified":"2026-06-13T12:40:38","modified_gmt":"2026-06-13T10:40:38","slug":"swantje-van-uehm-nui-cosmetics","status":"publish","type":"post","link":"https:\/\/startupvalley.news\/de\/swantje-van-uehm-nui-cosmetics\/","title":{"rendered":"Immer an sich selbst glauben"},"content":{"rendered":"\n<h2 class=\"wp-block-heading\">Swantje van Uehm Gr\u00fcnderin von NUI Cosmetics, High Performance Make-Up in stylischen Farben und modernem Design, in der H\u00f6hle der L\u00f6wen<\/h2>\n\n\n\n<h4 class=\"wp-block-heading\">Stellen Sie sich und das Startup NUI COSMETICS doch kurz vor!<\/h4>\n\n\n\n<p class=\"wp-block-paragraph\">Mein Name ist <a href=\"https:\/\/www.startupvalley.news\/de\/nui-cosmetics-make-up\/\" target=\"_blank\" rel=\"noreferrer noopener\" aria-label=\"Swantje van Uehm (\u00f6ffnet in neuem Tab)\">Swantje van Uehm<\/a> und ich habe NUI Cosmetics gegr\u00fcndet. Wir entwickeln exklusive, nachhaltige Beauty-Produkte. F\u00fcr starke Pers\u00f6nlichkeiten mit dem Wunsch nach einer Prise Luxus.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">NUI bietet nat\u00fcrliches, veganes und Glutenfreies High Performance Make-Up in stylischen Farben und modernem Design zu fairen Preisen. Das Wort \u201eNUI\u201c steht beim neuseel\u00e4ndischen Maori Volk f\u00fcr \u201egro\u00dfartig\u201c \u2013 und so soll sich jede*r Mensch mit NUI Cosmetics f\u00fchlen.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">THE STORY OF NUI \u2013 BE A PART OF SOMETHING PURE<\/p>\n\n\n\n<h4 class=\"wp-block-heading\">Wie ist die Idee zu NUI entstanden?<\/h4>\n\n\n\n<p class=\"wp-block-paragraph\">\u201eNaturkosmetik, Du?!\u201c &#8211; als ich damals in der Naturkosmetik Beauty Branche als Produkt und Brand Managerin anfing, bekam ich nicht selten verwunderte Reaktionen zu h\u00f6ren.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201e\u2026 so siehst du aber gar nicht aus\u201c. Ich arbeitete zuvor f\u00fcr Firmen wie Chanel im Produkt Management. Also ja, es stimmte, ich sah nicht so aus. Um mich so zu stylen, wie ich mich wohlf\u00fchtle, nutzte ich teils selbst noch synthetisches Make-Up. Ein Widerspruch, der mir bewusst war. Aber was war die Alternative?<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ich wollte vegane, nat\u00fcrliche Kosmetik und fand: Blasse Farben, br\u00f6selige Cremes, muffige D\u00fcfte &#8211; Hand aufs Herz: Viele nachhaltige Produkte waren gut gemeint, aber nicht gerade sexy. Einen leuchtenden, roten Lippenstift, ohne Karmin? Unm\u00f6glich. Nachhaltig und stylisch &#8211; das ging nicht. Beauty Boutique ODER Bio-Reformhaus.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Dazwischen lange nichts. Es sollte also noch ein paar Jahre dauern, bis ich auf einen veganen und trotzdem knallroten Lippenstift umsteigen w\u00fcrde. Denn: Ich musste ihn erst selbst entwickeln. Geboren war NUI. Seitdem sehen wir es als unsere Mission, der Beauty-Industrie neue Impulse zu liefern. Mit der Vision Naturkosmetik aus dem Staub von gestern zu befreien. Und klare Akzente zu setzen f\u00fcr eine bewusste und nachhaltige Zukunft, in der wir uns besser f\u00fchlen und aussehen als jemals zuvor.<\/p>\n\n\n\n<h4 class=\"wp-block-heading\">Welche Vision steckt hinter NUI?<\/h4>\n\n\n\n<p class=\"wp-block-paragraph\">Swantje van Uehm: Die NUI Vision: High-Performance-Naturkosmetik, die unserem Bed\u00fcrfnis nach \u00c4sthetik zu 100% gerecht wird und dabei clean, vegan und nachhaltig bleibt. Wir entwickeln schillernde, kr\u00e4ftige, moderne Farben, die im Kopf bleiben. Edle Texturen, die sich sanft an deine Haut schmiegen. Produkte, mit denen du dich wohlf\u00fchlst. Die du gerne ansiehst. Gerne riechst. Gerne auftr\u00e4gst. Wir wollen Conscious-Beauty, die Spa\u00df macht und zu deinem Lifestyle passt. Damit Du dich nicht st\u00e4ndig fragen musst, ob Du heute den Lieblingslippenstift oder das Gewissen zu Hause l\u00e4sst. Wir wollen nicht w\u00e4hlen m\u00fcssen zwischen \u00f6kologischem Bewusstsein und Freude an femininer Eleganz.<\/p>\n\n\n\n<h4 class=\"wp-block-heading\">Wer ist die Zielgruppe von NUI?<\/h4>\n\n\n\n<p class=\"wp-block-paragraph\">NUI ist f\u00fcr alle die Spa\u00df an Make up haben und auf nat\u00fcrliche Inhaltsstoffe Wert legen.&nbsp;<\/p>\n\n\n\n<h4 class=\"wp-block-heading\">Wie sind Sie auf die Idee gekommen sich f\u00fcr die Sendung Die H\u00f6hle der L\u00f6wen zu bewerben? Wie haben Sie sich auf die Sendung vorbereitet?<\/h4>\n\n\n\n<p class=\"wp-block-paragraph\">Neben NUI habe ich ein Unternehmen aufgebaut, welches parallel mehrere Absatzkan\u00e4le nutzt. Wir importieren internationale Premium-Naturkosmetik Marken und beliefern Business Partner in ganz Europas sowie Endkunden.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Wer mich kennt, wei\u00df das ich zu 180% hinter unseren Ideen stehe und seit 2015 entschlossen bin der Beauty Branche neue Impulse zu geben. Aber es ist mir auch wichtig zu zeigen, dass weibliche Gr\u00fcnderinnen alles schaffen k\u00f6nnen, wenn sie wollen.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ich bin einen klassischen Weg, inkl. Business Plan, vollem privaten Risiko und Bankkrediten gegangen. D.h. ich habe mich fr\u00fch daf\u00fcr entschieden die ersten 5 Jahre ohne Investoren zu arbeiten. Ich wollte mir unbedingt beweisen, dass ich die erste Million mit meinem Team alleine schaffe. Ich wollte ein gesundes, organisches Wachstum und ein profitables Unternehmen, bevor ich an Investoren herantreten w\u00fcrde.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Aber jetzt war die Zeit gekommen und ich habe DHDL als Chance genommen, um mich Investoren vorzustellen und gleichzeitig NUI einem breiten Publikum zu pr\u00e4sentieren.<\/p>\n\n\n\n<h4 class=\"wp-block-heading\">Sie sind eines der wenigen Startup Unternehmen, dass es in die Sendung Die H\u00f6hle der L\u00f6wen geschafft hat. Wie motivierend war das f\u00fcr Sie?Wie wichtig war dieser Schritt f\u00fcr Sie als Startup Unternehmen? Auch unter dem Gesichtspunkt, dass durch Die H\u00f6hle der L\u00f6wen viele Interessenten und auch Medien auf NUI aufmerksam werden? <\/h4>\n\n\n\n<p class=\"wp-block-paragraph\">Wer mich kennt, wei\u00df auch, dass ich neugierig bin und gerne dazulerne. Daher war DHDL f\u00fcr mich eine sehr gute Option wie gesagt das Interesse der Investoren auf NUI zu lenken und gleichzeitig unsere Marke diesem Publikum zu pr\u00e4sentieren. Die Aufmerksamkeit, die das Thema Conscious-Beauty dadurch bekommt, ist wirklich toll und f\u00fcr uns als Marke, aber auch f\u00fcr mich pers\u00f6nlich von sehr gro\u00dfem Wert.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Unsere Mission ist es, Naturkosmetik der breiten Masse zug\u00e4nglich zu machen und ich finde es gro\u00dfartig, mich mit Judith und ihrem Team auszutauschen und gemeinsam an neuen Ideen f\u00fcr NUI zu arbeiten.<\/p>\n\n\n\n<h4 class=\"wp-block-heading\">Welchen Investor hatten Sie im Fokus?<\/h4>\n\n\n\n<p class=\"wp-block-paragraph\">Ich war von Beginn an gegen\u00fcber allen L\u00f6wen offen, aber das Judith die gr\u00f6\u00dfte Expertise im Beauty Bereich hat ist klar. Daher war sie auch meine heimliche Favoritin, auch wenn ich gro\u00dfen Respekt davor hatte, NUI vor ihr zu pitchen.<\/p>\n\n\n\n<h4 class=\"wp-block-heading\">Swantje, wo geht der Weg hin? Wo sehen Sie sich in f\u00fcnf Jahren?<\/h4>\n\n\n\n<p class=\"wp-block-paragraph\">In 5 Jahren hoffe ich, dass ich noch mehr weibliche Gr\u00fcnder inspirieren konnte den Mut vor die Angst zu stellen. Wir werden weiter neue Impulse setzen, bis sich keiner mehr daran erinnern kann, dass es jemals anders war.<\/p>\n\n\n\n<h4 class=\"wp-block-heading\">Zum Schluss: Welche 3 Tipps w\u00fcrden Sie angehenden Gr\u00fcndern mit auf den Weg geben?<\/h4>\n\n\n\n<p class=\"wp-block-paragraph\">1. immer an sich selbst glauben, alles wird gut&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">2. keine L\u00f6sung ist keine L\u00f6sung&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">3. auf das Bauchgef\u00fchl h\u00f6ren&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Bild: Swantje van Uehm aus Berlin pr\u00e4sentiert mit &#8222;NUI Cosmetics&#8220; glamour\u00f6se Naturkosmetik. Sie erhofft sich ein Investment von 250.000 Euro f\u00fcr 20 Prozent der Anteile an ihrem Unternehmen. <br>Foto: TVNOW \/ Bernd-Michael Maurer<\/p>\n\n\n\n<h4 class=\"wp-block-heading\">Sehen Sie NUI Cosmetics am 19. Oktober in der H\u00f6hle der L\u00f6wen<\/h4>\n\n\n\n<p class=\"wp-block-paragraph\">Weitere Informationen finden Sie&nbsp;<a rel=\"noreferrer noopener\" href=\"https:\/\/nuicosmetics.com\/\" target=\"_blank\">hier<\/a><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Wir bedanken uns bei Swantje van Uehm f\u00fcr das Interview<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Aussagen des Autors und des Interviewpartners geben nicht unbedingt die Meinung der Redaktion und des Verlags wieder<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Swantje van Uehm Gr\u00fcnderin von NUI Cosmetics, High Performance Make-Up in stylischen Farben und modernem Design, in der H\u00f6hle der L\u00f6wen<\/p>\n","protected":false},"author":9,"featured_media":73015,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[6430,26473],"tags":[4974,1667,1374,13562],"class_list":["post-73014","post","type-post","status-publish","format-standard","has-post-thumbnail","category-female-founders","category-interviews","tag-beauty","tag-make-up","tag-naturkosmetik","tag-nui"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.3 (Yoast SEO v28.3) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Swantje van Uehm NUI Cosmetics Naturkosmetik<\/title>\n<meta name=\"description\" content=\"Swantje van Uehm Gr\u00fcnderin von NUI Cosmetics, High Performance Make-Up in stylischen Farben und modernem Design, in der H\u00f6hle der L\u00f6wen\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/startupvalley.news\/de\/swantje-van-uehm-nui-cosmetics\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Immer an sich selbst glauben\" \/>\n<meta property=\"og:description\" content=\"Swantje van Uehm Gr\u00fcnderin von NUI Cosmetics, High Performance Make-Up in stylischen Farben und modernem Design, in der H\u00f6hle der L\u00f6wen\" \/>\n<meta property=\"og:url\" content=\"https:\/\/startupvalley.news\/de\/swantje-van-uehm-nui-cosmetics\/\" \/>\n<meta property=\"og:site_name\" content=\"StartupValley\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/startupvalleynews\" \/>\n<meta property=\"article:published_time\" content=\"2020-10-18T22:01:55+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-06-13T10:40:38+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/startupvalley.news\/de\/wp-content\/uploads\/sites\/2\/2020\/10\/nui-cosmetics.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"677\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"StartupValley\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@startup_valley\" \/>\n<meta name=\"twitter:site\" content=\"@startup_valley\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"StartupValley\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"6\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\\\/\\\/startupvalley.news\\\/de\\\/swantje-van-uehm-nui-cosmetics\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/startupvalley.news\\\/de\\\/swantje-van-uehm-nui-cosmetics\\\/\"},\"author\":{\"name\":\"StartupValley\",\"@id\":\"https:\\\/\\\/startupvalley.news\\\/de\\\/#\\\/schema\\\/person\\\/dc9abc71daa8d949d4f257f2e9883e00\"},\"headline\":\"Immer an sich selbst glauben\",\"datePublished\":\"2020-10-18T22:01:55+00:00\",\"dateModified\":\"2026-06-13T10:40:38+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/startupvalley.news\\\/de\\\/swantje-van-uehm-nui-cosmetics\\\/\"},\"wordCount\":1047,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/startupvalley.news\\\/de\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/startupvalley.news\\\/de\\\/swantje-van-uehm-nui-cosmetics\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/startupvalley.news\\\/de\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2020\\\/10\\\/nui-cosmetics.jpg\",\"keywords\":[\"Beauty\",\"Make up\",\"Naturkosmetik\",\"NUI\"],\"articleSection\":[\"Female Founders\",\"Interviews\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/startupvalley.news\\\/de\\\/swantje-van-uehm-nui-cosmetics\\\/#respond\"]}],\"copyrightYear\":\"2020\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/startupvalley.news\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/startupvalley.news\\\/de\\\/swantje-van-uehm-nui-cosmetics\\\/\",\"url\":\"https:\\\/\\\/startupvalley.news\\\/de\\\/swantje-van-uehm-nui-cosmetics\\\/\",\"name\":\"Swantje van Uehm NUI Cosmetics Naturkosmetik\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/startupvalley.news\\\/de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/startupvalley.news\\\/de\\\/swantje-van-uehm-nui-cosmetics\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/startupvalley.news\\\/de\\\/swantje-van-uehm-nui-cosmetics\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/startupvalley.news\\\/de\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2020\\\/10\\\/nui-cosmetics.jpg\",\"datePublished\":\"2020-10-18T22:01:55+00:00\",\"dateModified\":\"2026-06-13T10:40:38+00:00\",\"description\":\"Swantje van Uehm Gr\u00fcnderin von NUI Cosmetics, High Performance Make-Up in stylischen Farben und modernem Design, in der H\u00f6hle der L\u00f6wen\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/startupvalley.news\\\/de\\\/swantje-van-uehm-nui-cosmetics\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/startupvalley.news\\\/de\\\/swantje-van-uehm-nui-cosmetics\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/startupvalley.news\\\/de\\\/swantje-van-uehm-nui-cosmetics\\\/#primaryimage\",\"url\":\"https:\\\/\\\/startupvalley.news\\\/de\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2020\\\/10\\\/nui-cosmetics.jpg\",\"contentUrl\":\"https:\\\/\\\/startupvalley.news\\\/de\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2020\\\/10\\\/nui-cosmetics.jpg\",\"width\":1200,\"height\":677,\"caption\":\"Swantje van Uehm NUI Cosmetics Naturkosmetik in der H\u00f6hle der L\u00f6wen\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/startupvalley.news\\\/de\\\/swantje-van-uehm-nui-cosmetics\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/startupvalley.news\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Immer an sich selbst glauben\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/startupvalley.news\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/startupvalley.news\\\/de\\\/\",\"name\":\"StartupValley\",\"description\":\"Startup-News, Funding &amp; Gr\u00fcnder-Interviews\",\"publisher\":{\"@id\":\"https:\\\/\\\/startupvalley.news\\\/de\\\/#organization\"},\"alternateName\":\"StartupValley Magazin\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/startupvalley.news\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/startupvalley.news\\\/de\\\/#organization\",\"name\":\"StartupValley Media\",\"url\":\"https:\\\/\\\/startupvalley.news\\\/de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/startupvalley.news\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/startupvalley.news\\\/de\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2020\\\/12\\\/StartupValley-LOGO-neu-retina.png\",\"contentUrl\":\"https:\\\/\\\/startupvalley.news\\\/de\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2020\\\/12\\\/StartupValley-LOGO-neu-retina.png\",\"width\":460,\"height\":180,\"caption\":\"StartupValley Media\"},\"image\":{\"@id\":\"https:\\\/\\\/startupvalley.news\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/startupvalleynews\",\"https:\\\/\\\/x.com\\\/startup_valley\",\"https:\\\/\\\/www.twitch.tv\\\/startupvalley\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/startupvalleymagazine\",\"https:\\\/\\\/www.instagram.com\\\/startup_valley\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/startupvalley.news\\\/de\\\/#\\\/schema\\\/person\\\/dc9abc71daa8d949d4f257f2e9883e00\",\"name\":\"StartupValley\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6436ca57465a88bfa716825ebdd3bc23f850aaaa3a51d16da34504822452fa3a?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6436ca57465a88bfa716825ebdd3bc23f850aaaa3a51d16da34504822452fa3a?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6436ca57465a88bfa716825ebdd3bc23f850aaaa3a51d16da34504822452fa3a?s=96&d=mm&r=g\",\"caption\":\"StartupValley\"},\"description\":\"Das StartupValley Magazin ist Europas gro\u00dfes Magazin f\u00fcr Start-ups, Gr\u00fcnder und Entrepreneure. Ihr findet bei uns Tagesaktuelle News zu den neuesten Trends, Technologien und Gesch\u00e4ftsmodellen der internationalen Startup-Szene sowie Interviews mit erfolgreichen Gr\u00fcndern und Investoren.\",\"url\":\"https:\\\/\\\/startupvalley.news\\\/de\\\/author\\\/redaktion\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Swantje van Uehm NUI Cosmetics Naturkosmetik","description":"Swantje van Uehm Gr\u00fcnderin von NUI Cosmetics, High Performance Make-Up in stylischen Farben und modernem Design, in der H\u00f6hle der L\u00f6wen","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/startupvalley.news\/de\/swantje-van-uehm-nui-cosmetics\/","og_locale":"de_DE","og_type":"article","og_title":"Immer an sich selbst glauben","og_description":"Swantje van Uehm Gr\u00fcnderin von NUI Cosmetics, High Performance Make-Up in stylischen Farben und modernem Design, in der H\u00f6hle der L\u00f6wen","og_url":"https:\/\/startupvalley.news\/de\/swantje-van-uehm-nui-cosmetics\/","og_site_name":"StartupValley","article_publisher":"https:\/\/www.facebook.com\/startupvalleynews","article_published_time":"2020-10-18T22:01:55+00:00","article_modified_time":"2026-06-13T10:40:38+00:00","og_image":[{"width":1200,"height":677,"url":"https:\/\/startupvalley.news\/de\/wp-content\/uploads\/sites\/2\/2020\/10\/nui-cosmetics.jpg","type":"image\/jpeg"}],"author":"StartupValley","twitter_card":"summary_large_image","twitter_creator":"@startup_valley","twitter_site":"@startup_valley","twitter_misc":{"Verfasst von":"StartupValley","Gesch\u00e4tzte Lesezeit":"6\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/startupvalley.news\/de\/swantje-van-uehm-nui-cosmetics\/#article","isPartOf":{"@id":"https:\/\/startupvalley.news\/de\/swantje-van-uehm-nui-cosmetics\/"},"author":{"name":"StartupValley","@id":"https:\/\/startupvalley.news\/de\/#\/schema\/person\/dc9abc71daa8d949d4f257f2e9883e00"},"headline":"Immer an sich selbst glauben","datePublished":"2020-10-18T22:01:55+00:00","dateModified":"2026-06-13T10:40:38+00:00","mainEntityOfPage":{"@id":"https:\/\/startupvalley.news\/de\/swantje-van-uehm-nui-cosmetics\/"},"wordCount":1047,"commentCount":0,"publisher":{"@id":"https:\/\/startupvalley.news\/de\/#organization"},"image":{"@id":"https:\/\/startupvalley.news\/de\/swantje-van-uehm-nui-cosmetics\/#primaryimage"},"thumbnailUrl":"https:\/\/startupvalley.news\/de\/wp-content\/uploads\/sites\/2\/2020\/10\/nui-cosmetics.jpg","keywords":["Beauty","Make up","Naturkosmetik","NUI"],"articleSection":["Female Founders","Interviews"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/startupvalley.news\/de\/swantje-van-uehm-nui-cosmetics\/#respond"]}],"copyrightYear":"2020","copyrightHolder":{"@id":"https:\/\/startupvalley.news\/#organization"}},{"@type":"WebPage","@id":"https:\/\/startupvalley.news\/de\/swantje-van-uehm-nui-cosmetics\/","url":"https:\/\/startupvalley.news\/de\/swantje-van-uehm-nui-cosmetics\/","name":"Swantje van Uehm NUI Cosmetics Naturkosmetik","isPartOf":{"@id":"https:\/\/startupvalley.news\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/startupvalley.news\/de\/swantje-van-uehm-nui-cosmetics\/#primaryimage"},"image":{"@id":"https:\/\/startupvalley.news\/de\/swantje-van-uehm-nui-cosmetics\/#primaryimage"},"thumbnailUrl":"https:\/\/startupvalley.news\/de\/wp-content\/uploads\/sites\/2\/2020\/10\/nui-cosmetics.jpg","datePublished":"2020-10-18T22:01:55+00:00","dateModified":"2026-06-13T10:40:38+00:00","description":"Swantje van Uehm Gr\u00fcnderin von NUI Cosmetics, High Performance Make-Up in stylischen Farben und modernem Design, in der H\u00f6hle der L\u00f6wen","breadcrumb":{"@id":"https:\/\/startupvalley.news\/de\/swantje-van-uehm-nui-cosmetics\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/startupvalley.news\/de\/swantje-van-uehm-nui-cosmetics\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/startupvalley.news\/de\/swantje-van-uehm-nui-cosmetics\/#primaryimage","url":"https:\/\/startupvalley.news\/de\/wp-content\/uploads\/sites\/2\/2020\/10\/nui-cosmetics.jpg","contentUrl":"https:\/\/startupvalley.news\/de\/wp-content\/uploads\/sites\/2\/2020\/10\/nui-cosmetics.jpg","width":1200,"height":677,"caption":"Swantje van Uehm NUI Cosmetics Naturkosmetik in der H\u00f6hle der L\u00f6wen"},{"@type":"BreadcrumbList","@id":"https:\/\/startupvalley.news\/de\/swantje-van-uehm-nui-cosmetics\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/startupvalley.news\/de\/"},{"@type":"ListItem","position":2,"name":"Immer an sich selbst glauben"}]},{"@type":"WebSite","@id":"https:\/\/startupvalley.news\/de\/#website","url":"https:\/\/startupvalley.news\/de\/","name":"StartupValley","description":"Startup-News, Funding &amp; Gr\u00fcnder-Interviews","publisher":{"@id":"https:\/\/startupvalley.news\/de\/#organization"},"alternateName":"StartupValley Magazin","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/startupvalley.news\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/startupvalley.news\/de\/#organization","name":"StartupValley Media","url":"https:\/\/startupvalley.news\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/startupvalley.news\/de\/#\/schema\/logo\/image\/","url":"https:\/\/startupvalley.news\/de\/wp-content\/uploads\/sites\/2\/2020\/12\/StartupValley-LOGO-neu-retina.png","contentUrl":"https:\/\/startupvalley.news\/de\/wp-content\/uploads\/sites\/2\/2020\/12\/StartupValley-LOGO-neu-retina.png","width":460,"height":180,"caption":"StartupValley Media"},"image":{"@id":"https:\/\/startupvalley.news\/de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/startupvalleynews","https:\/\/x.com\/startup_valley","https:\/\/www.twitch.tv\/startupvalley","https:\/\/www.linkedin.com\/company\/startupvalleymagazine","https:\/\/www.instagram.com\/startup_valley"]},{"@type":"Person","@id":"https:\/\/startupvalley.news\/de\/#\/schema\/person\/dc9abc71daa8d949d4f257f2e9883e00","name":"StartupValley","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/6436ca57465a88bfa716825ebdd3bc23f850aaaa3a51d16da34504822452fa3a?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/6436ca57465a88bfa716825ebdd3bc23f850aaaa3a51d16da34504822452fa3a?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/6436ca57465a88bfa716825ebdd3bc23f850aaaa3a51d16da34504822452fa3a?s=96&d=mm&r=g","caption":"StartupValley"},"description":"Das StartupValley Magazin ist Europas gro\u00dfes Magazin f\u00fcr Start-ups, Gr\u00fcnder und Entrepreneure. Ihr findet bei uns Tagesaktuelle News zu den neuesten Trends, Technologien und Gesch\u00e4ftsmodellen der internationalen Startup-Szene sowie Interviews mit erfolgreichen Gr\u00fcndern und Investoren.","url":"https:\/\/startupvalley.news\/de\/author\/redaktion\/"}]}},"_links":{"self":[{"href":"https:\/\/startupvalley.news\/de\/wp-json\/wp\/v2\/posts\/73014","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/startupvalley.news\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/startupvalley.news\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/startupvalley.news\/de\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/startupvalley.news\/de\/wp-json\/wp\/v2\/comments?post=73014"}],"version-history":[{"count":1,"href":"https:\/\/startupvalley.news\/de\/wp-json\/wp\/v2\/posts\/73014\/revisions"}],"predecessor-version":[{"id":111952,"href":"https:\/\/startupvalley.news\/de\/wp-json\/wp\/v2\/posts\/73014\/revisions\/111952"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/startupvalley.news\/de\/wp-json\/wp\/v2\/media\/73015"}],"wp:attachment":[{"href":"https:\/\/startupvalley.news\/de\/wp-json\/wp\/v2\/media?parent=73014"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/startupvalley.news\/de\/wp-json\/wp\/v2\/categories?post=73014"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/startupvalley.news\/de\/wp-json\/wp\/v2\/tags?post=73014"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}