{"id":91876,"date":"2022-11-03T08:20:00","date_gmt":"2022-11-03T07:20:00","guid":{"rendered":"https:\/\/www.startupvalley.news\/de\/?p=91876"},"modified":"2026-06-13T10:08:54","modified_gmt":"2026-06-13T08:08:54","slug":"gerdaxdoris-online-coaching-business","status":"publish","type":"post","link":"https:\/\/startupvalley.news\/de\/gerdaxdoris-online-coaching-business\/","title":{"rendered":"Du brauchst eine Menge Vertrauen in Dich und viel Gelassenheit"},"content":{"rendered":"\n<h2 class=\"wp-block-heading\">GerdaxDoris: Online Coaching Business \u00fcber Social Media Marketing und Businessaufbau<\/h2>\n\n\n\n<h4 class=\"wp-block-heading\">Stellen Sie sich und das Startup Gerdaxdoris doch kurz unseren Lesern vor!<\/h4>\n\n\n\n<p class=\"wp-block-paragraph\">GerdaxDoris ist das Produkt von meinem Spa\u00df am unternehmerischen Erfolg.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ich will Business Frauen und ihre Missionen bl\u00fchen sehen: Gro\u00dfartige Communities und Movements, die bei meinen Kundinnen entstehen und finanziell unabh\u00e4ngige Senkrechtstarterinnen produzieren. Unsere Lieblings-Zutaten dazu: Authentizit\u00e4t, eine echte Perfect-Match Positionierung und Content, der die richtigen Menschen mitten ins Herz trifft. Der Lieblings-Spielplatz? Instagram! Ich entwickle mit ihnen die richtige Mischung von Intuition und Strategie f\u00fcr ihren Erfolg.<\/p>\n\n\n\n<h4 class=\"wp-block-heading\">Warum haben Sie sich entschlossen, ein Unternehmen zu gr\u00fcnden?<\/h4>\n\n\n\n<p class=\"wp-block-paragraph\">Oh, ganz ehrlich? Unternehmertum liegt mir im Blut. Meine Eltern haben mir das damals auch vorgelebt &#8211; ohne mich zu pampern, aber Unterst\u00fctzung bei dieser Entscheidung ist wirklich Gold wert!<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Mein erstes Startup hat sich noch um ein Design-Produkt gedreht, das war ein gro\u00dfartiger Lehrmeister, wie die Businesswelt so funktioniert. Im Online Coaching kommt aber dazu, dass man die Regeln f\u00fcr die eigene Karriere, den eigenen Lifestyle selbst schrieben kann.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Meine Hauptmotivation, diesen Weg zu gehen sind sowohl finanzielle als auch gestalterische Freiheit in meinem Leben. Ich setze die Segel, ich arbeite wann und von wo aus ich will. Dieses \u201eWarum\u201c f\u00fcr meine Gr\u00fcndung und den weiteren Weg finde ich f\u00fcr mich immer noch unschlagbar sch\u00f6n!<\/p>\n\n\n\n<h4 class=\"wp-block-heading\">Was war bei der Gr\u00fcndung von Gerdaxdoris die gr\u00f6\u00dfte Herausforderung?<\/h4>\n\n\n\n<p class=\"wp-block-paragraph\">Absolute Ahnungslosigkeit! Das ganze Wissen, das man sich irgendwie aneignen muss, weil es weder in der Schule noch im Studium die entsprechende Vorbereitung gibt. Auch, sich alles auf einmal anzulesen ist schier unm\u00f6glich. Welche Unterlagen braucht der Steuerberater wann? Wieviel Geld kann ich ausgeben, was muss ich zur\u00fccklegen? Wie schlimm ist es, wenn ich hier einen Fehler mache? Das beste Rezept dagegen ist glaube ich ein bisschen Wahnsinn, sehr viel Gottvertrauen und am allerbesten, ein Mentor, der einen durch die Praxis begleitet.<\/p>\n\n\n\n<h4 class=\"wp-block-heading\">Kann man mit einer Idee starten, wenn noch nicht alles perfekt ist?<\/h4>\n\n\n\n<p class=\"wp-block-paragraph\">Das w\u00fcrde ich sogar dringend empfehlen! Wenn noch nicht zu viel Arbeit, Geld und Zeit in ein Projekt geflossen ist lastet viel weniger Druck darauf, es gibt keinen \u201edo or die\u201c Moment. Ich habe damals z.B. w\u00e4hrend dem Studium einfach gegr\u00fcndet und mich schrittweise vorgearbeitet. Das war die beste Entscheidung! Das Fallnetz, die Sicherung war ja da. Deswegen bin ich auch ein gro\u00dfer Freund von Gr\u00fcndungen, die erstmal nebenher laufen.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Am Ende ist der eigene Kopf oft der gr\u00f6\u00dfte Stolperstein, und wenn man Herausforderungen gelassen begeben kann und nicht gleich in Angst oder Mangeldenken (Ohgott, ich brauch doch jetzt sofort Kunden!) rutscht, dann kann das eine gro\u00dfe Abk\u00fcrzung sein.<\/p>\n\n\n\n<h4 class=\"wp-block-heading\">Welche Vision steckt hinter Gerdaxdoris?<\/h4>\n\n\n\n<p class=\"wp-block-paragraph\">Wenn Menschen Dir zuh\u00f6ren, und wissen, dass sie bei Dir genau richtig sind- dann ist es ein Kinderspiel, Dein Angebot zu verkaufen! Meine Vision vom Marketing der neuen Zeit ist, die richtigen Menschen zusammenzubringen. Die Verbissenheit und Angestrengtheit aus dem Marketing raus zu nehmen. Den Menschen zu zeigen, wie sie sich etwas aufbauen, bei dem die Ernte nicht erst in der Rente wartet, sondern wie sie jeden Tag an ihrer Mission bauen, die sie lieben und die sie erf\u00fcllt.<\/p>\n\n\n\n<h4 class=\"wp-block-heading\">Wer ist die Zielgruppe von Gerdaxdoris?<\/h4>\n\n\n\n<p class=\"wp-block-paragraph\">Ich arbeite mit Frauen, Unternehmerinnen, die denken \u201eHey, wenn die mir endlich mal zuh\u00f6ren w\u00fcrden, dann w\u00fcrden wir die krassesten Erfolge feiern\u201c wenn sie an ihre potentiellen Kunden denken. Die sich in ihrem \u201eangelernten\u201c Weg, Marketing und Content zu machen nicht mehr wiederfinden. Die f\u00fchlen, dass sie noch mehr zu rei\u00dfen haben als das, was im Moment von ihnen zu sehen ist.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Kurz: Ich suche nach meinen Business Rockstars in spe<\/p>\n\n\n\n<h4 class=\"wp-block-heading\">Wo liegen die Vorteile? Was unterscheidet Sie von anderen Anbietern?<\/h4>\n\n\n\n<p class=\"wp-block-paragraph\">Heutzutage gibt es vor allem unter den Big Playern im Agentur und Coaching Business viele, die Blueprint L\u00f6sung verkaufen und antrainieren. Da z\u00e4hlen Schlagzahl und \u201eDisziplin\u201c.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Aber was ist, wenn das Kind krank war? Oder es ein t\u00e4glicher Kampf wird, weil es einfach keinen Spa\u00df mehr macht? Da hei\u00dft es oft: \u201eDa muss man halt durch.\u201c Bulls*t sage ich. Wir bauen Unternehmen, die UNS tragen, nicht umgekehrt. Wir bauen doch nicht an unserem eigenen goldenen K\u00e4fig!<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Klar wollen wir auch die 5- und 6 stelligen Monatsums\u00e4tze; Aber grade uns Frauen ist meistens unsere Lebensqualit\u00e4t, unsere Beziehungen, unsere Familien genauso eine Priorit\u00e4t und Entwicklungsfeld. Bei uns schrieben wir selbst die Regeln und suchen kreative Wege.<\/p>\n\n\n\n<h4 class=\"wp-block-heading\">Gerdaxdoris, wo geht der Weg hin? Wo sehen Sie sich in f\u00fcnf Jahren?<\/h4>\n\n\n\n<p class=\"wp-block-paragraph\">In 5 Jahren stehe ich auf der Forbes Liste 30 unter 30. Das ist mein pers\u00f6nliches Ziel. GerdaxDoris soll dann f\u00fcr jede Frau im Online Business ihr Missing Piece liefern, dass sie in den Moment braucht- wir arbeiten an einer Angebotspalette von punktuellen Masterclasses, die aber so On Point sind, dass sie Probleme zuverl\u00e4ssig l\u00f6sen, \u00fcber Coachingprogramme, in denen die n\u00e4chsten Erfolgsgeschichten entstehen und Langzeitbegleitungen, in denen eigene kleine Imperien gro\u00df gemacht werden.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ich m\u00f6chte mit meinem Unternehmen Projekte schaffen und unterst\u00fctzen, die unserer Welt, den Menschen und der Umwelt etwas zur\u00fcckgeben. Schon heute unterst\u00fctzen wir solche Projekte, das m\u00f6chte ich wieder vorantreiben.<\/p>\n\n\n\n<h4 class=\"wp-block-heading\">Zum Schluss: Welche 3 Tipps w\u00fcrden Sie angehenden Gr\u00fcnderinnen mit auf den Weg geben?<\/h4>\n\n\n\n<p class=\"wp-block-paragraph\">Erstens: Sei mutig, pass auf Deinen Kopf, Dein Mindset, Deine Einstellung auf: Du brauchst eine Menge Vertrauen in Dich und viel Gelassenheit, um auf den Wellen des Lebens als Unternehmerin surfen zu lernen.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Zweitens: Schaff Dir ein Umfeld, das Dich unterst\u00fctzt: Menschen, die an Dich glauben und von denen Du wei\u00dft, dass Du im Notfall mal eine Weile aufgefangen werden w\u00fcrdest. Routinen, die Dich fit, satt, klar im Kopf halten.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Drittens: Folge dem Spa\u00df. Du machst das f\u00fcr Dich, und f\u00fcr niemand anderen. Finde heraus, was Dich antreibt. Nicht das \u201eThema\u201c, sondern das Gef\u00fchl: Liebst Du besonders knifflige Detail-F\u00e4lle? Liebst Du es, immer wieder kleine Erfolge zu sehen? Liebst Du es, die Reise mit jemandem zu teilen? Sorge daf\u00fcr, dass Deine Flamme am brennen gehalten wird!<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Wir bedanken uns bei Barbara Streit f\u00fcr das Interview<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Aussagen des Autors und des Interviewpartners geben nicht unbedingt die Meinung der Redaktion und des Verlags wieder<\/p>\n","protected":false},"excerpt":{"rendered":"<p>GerdaxDoris: Online Coaching Business \u00fcber Social Media Marketing und Businessaufbau- die richtige Mischung von Intuition und Strategie f\u00fcr ihren Erfolg.<\/p>\n","protected":false},"author":9,"featured_media":92477,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[6430,26473],"tags":[1076,460,3153,491,2310],"class_list":["post-91876","post","type-post","status-publish","format-standard","has-post-thumbnail","category-female-founders","category-interviews","tag-business","tag-coaching","tag-erfolg","tag-social-media","tag-social-media-marketing"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.3 (Yoast SEO v28.3) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>GerdaxDoris: Online Coaching Business Social Media Marketing<\/title>\n<meta name=\"description\" content=\"GerdaxDoris: Online Coaching Business \u00fcber Social Media Marketing und Businessaufbau- die richtige Mischung von Intuition und Strategie\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/startupvalley.news\/de\/gerdaxdoris-online-coaching-business\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Du brauchst eine Menge Vertrauen in Dich und viel Gelassenheit\" \/>\n<meta property=\"og:description\" content=\"GerdaxDoris: Online Coaching Business \u00fcber Social Media Marketing und Businessaufbau- die richtige Mischung von Intuition und Strategie\" \/>\n<meta property=\"og:url\" content=\"https:\/\/startupvalley.news\/de\/gerdaxdoris-online-coaching-business\/\" \/>\n<meta property=\"og:site_name\" content=\"StartupValley\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/startupvalleynews\" \/>\n<meta property=\"article:published_time\" content=\"2022-11-03T07:20:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-06-13T08:08:54+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/startupvalley.news\/de\/wp-content\/uploads\/sites\/2\/2022\/10\/Barbara-Streit.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"680\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"StartupValley\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@startup_valley\" \/>\n<meta name=\"twitter:site\" content=\"@startup_valley\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"StartupValley\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"6\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\\\/\\\/startupvalley.news\\\/de\\\/gerdaxdoris-online-coaching-business\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/startupvalley.news\\\/de\\\/gerdaxdoris-online-coaching-business\\\/\"},\"author\":{\"name\":\"StartupValley\",\"@id\":\"https:\\\/\\\/startupvalley.news\\\/de\\\/#\\\/schema\\\/person\\\/dc9abc71daa8d949d4f257f2e9883e00\"},\"headline\":\"Du brauchst eine Menge Vertrauen in Dich und viel Gelassenheit\",\"datePublished\":\"2022-11-03T07:20:00+00:00\",\"dateModified\":\"2026-06-13T08:08:54+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/startupvalley.news\\\/de\\\/gerdaxdoris-online-coaching-business\\\/\"},\"wordCount\":1066,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/startupvalley.news\\\/de\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/startupvalley.news\\\/de\\\/gerdaxdoris-online-coaching-business\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/startupvalley.news\\\/de\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/10\\\/Barbara-Streit.jpg\",\"keywords\":[\"Business\",\"Coaching\",\"Erfolg\",\"social media\",\"Social Media Marketing\"],\"articleSection\":[\"Female Founders\",\"Interviews\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/startupvalley.news\\\/de\\\/gerdaxdoris-online-coaching-business\\\/#respond\"]}],\"copyrightYear\":\"2022\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/startupvalley.news\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/startupvalley.news\\\/de\\\/gerdaxdoris-online-coaching-business\\\/\",\"url\":\"https:\\\/\\\/startupvalley.news\\\/de\\\/gerdaxdoris-online-coaching-business\\\/\",\"name\":\"GerdaxDoris: Online Coaching Business Social Media Marketing\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/startupvalley.news\\\/de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/startupvalley.news\\\/de\\\/gerdaxdoris-online-coaching-business\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/startupvalley.news\\\/de\\\/gerdaxdoris-online-coaching-business\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/startupvalley.news\\\/de\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/10\\\/Barbara-Streit.jpg\",\"datePublished\":\"2022-11-03T07:20:00+00:00\",\"dateModified\":\"2026-06-13T08:08:54+00:00\",\"description\":\"GerdaxDoris: Online Coaching Business \u00fcber Social Media Marketing und Businessaufbau- die richtige Mischung von Intuition und Strategie\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/startupvalley.news\\\/de\\\/gerdaxdoris-online-coaching-business\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/startupvalley.news\\\/de\\\/gerdaxdoris-online-coaching-business\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/startupvalley.news\\\/de\\\/gerdaxdoris-online-coaching-business\\\/#primaryimage\",\"url\":\"https:\\\/\\\/startupvalley.news\\\/de\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/10\\\/Barbara-Streit.jpg\",\"contentUrl\":\"https:\\\/\\\/startupvalley.news\\\/de\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/10\\\/Barbara-Streit.jpg\",\"width\":1200,\"height\":680,\"caption\":\"GerdaxDoris: Online Coaching Business \u00fcber Social Media Marketing\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/startupvalley.news\\\/de\\\/gerdaxdoris-online-coaching-business\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/startupvalley.news\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Du brauchst eine Menge Vertrauen in Dich und viel Gelassenheit\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/startupvalley.news\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/startupvalley.news\\\/de\\\/\",\"name\":\"StartupValley\",\"description\":\"Startup-News, Funding &amp; Gr\u00fcnder-Interviews\",\"publisher\":{\"@id\":\"https:\\\/\\\/startupvalley.news\\\/de\\\/#organization\"},\"alternateName\":\"StartupValley Magazin\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/startupvalley.news\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/startupvalley.news\\\/de\\\/#organization\",\"name\":\"StartupValley Media\",\"url\":\"https:\\\/\\\/startupvalley.news\\\/de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/startupvalley.news\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/startupvalley.news\\\/de\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2020\\\/12\\\/StartupValley-LOGO-neu-retina.png\",\"contentUrl\":\"https:\\\/\\\/startupvalley.news\\\/de\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2020\\\/12\\\/StartupValley-LOGO-neu-retina.png\",\"width\":460,\"height\":180,\"caption\":\"StartupValley Media\"},\"image\":{\"@id\":\"https:\\\/\\\/startupvalley.news\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/startupvalleynews\",\"https:\\\/\\\/x.com\\\/startup_valley\",\"https:\\\/\\\/www.twitch.tv\\\/startupvalley\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/startupvalleymagazine\",\"https:\\\/\\\/www.instagram.com\\\/startup_valley\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/startupvalley.news\\\/de\\\/#\\\/schema\\\/person\\\/dc9abc71daa8d949d4f257f2e9883e00\",\"name\":\"StartupValley\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6436ca57465a88bfa716825ebdd3bc23f850aaaa3a51d16da34504822452fa3a?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6436ca57465a88bfa716825ebdd3bc23f850aaaa3a51d16da34504822452fa3a?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6436ca57465a88bfa716825ebdd3bc23f850aaaa3a51d16da34504822452fa3a?s=96&d=mm&r=g\",\"caption\":\"StartupValley\"},\"description\":\"Das StartupValley Magazin ist Europas gro\u00dfes Magazin f\u00fcr Start-ups, Gr\u00fcnder und Entrepreneure. Ihr findet bei uns Tagesaktuelle News zu den neuesten Trends, Technologien und Gesch\u00e4ftsmodellen der internationalen Startup-Szene sowie Interviews mit erfolgreichen Gr\u00fcndern und Investoren.\",\"url\":\"https:\\\/\\\/startupvalley.news\\\/de\\\/author\\\/redaktion\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"GerdaxDoris: Online Coaching Business Social Media Marketing","description":"GerdaxDoris: Online Coaching Business \u00fcber Social Media Marketing und Businessaufbau- die richtige Mischung von Intuition und Strategie","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/startupvalley.news\/de\/gerdaxdoris-online-coaching-business\/","og_locale":"de_DE","og_type":"article","og_title":"Du brauchst eine Menge Vertrauen in Dich und viel Gelassenheit","og_description":"GerdaxDoris: Online Coaching Business \u00fcber Social Media Marketing und Businessaufbau- die richtige Mischung von Intuition und Strategie","og_url":"https:\/\/startupvalley.news\/de\/gerdaxdoris-online-coaching-business\/","og_site_name":"StartupValley","article_publisher":"https:\/\/www.facebook.com\/startupvalleynews","article_published_time":"2022-11-03T07:20:00+00:00","article_modified_time":"2026-06-13T08:08:54+00:00","og_image":[{"width":1200,"height":680,"url":"https:\/\/startupvalley.news\/de\/wp-content\/uploads\/sites\/2\/2022\/10\/Barbara-Streit.jpg","type":"image\/jpeg"}],"author":"StartupValley","twitter_card":"summary_large_image","twitter_creator":"@startup_valley","twitter_site":"@startup_valley","twitter_misc":{"Verfasst von":"StartupValley","Gesch\u00e4tzte Lesezeit":"6\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/startupvalley.news\/de\/gerdaxdoris-online-coaching-business\/#article","isPartOf":{"@id":"https:\/\/startupvalley.news\/de\/gerdaxdoris-online-coaching-business\/"},"author":{"name":"StartupValley","@id":"https:\/\/startupvalley.news\/de\/#\/schema\/person\/dc9abc71daa8d949d4f257f2e9883e00"},"headline":"Du brauchst eine Menge Vertrauen in Dich und viel Gelassenheit","datePublished":"2022-11-03T07:20:00+00:00","dateModified":"2026-06-13T08:08:54+00:00","mainEntityOfPage":{"@id":"https:\/\/startupvalley.news\/de\/gerdaxdoris-online-coaching-business\/"},"wordCount":1066,"commentCount":0,"publisher":{"@id":"https:\/\/startupvalley.news\/de\/#organization"},"image":{"@id":"https:\/\/startupvalley.news\/de\/gerdaxdoris-online-coaching-business\/#primaryimage"},"thumbnailUrl":"https:\/\/startupvalley.news\/de\/wp-content\/uploads\/sites\/2\/2022\/10\/Barbara-Streit.jpg","keywords":["Business","Coaching","Erfolg","social media","Social Media Marketing"],"articleSection":["Female Founders","Interviews"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/startupvalley.news\/de\/gerdaxdoris-online-coaching-business\/#respond"]}],"copyrightYear":"2022","copyrightHolder":{"@id":"https:\/\/startupvalley.news\/#organization"}},{"@type":"WebPage","@id":"https:\/\/startupvalley.news\/de\/gerdaxdoris-online-coaching-business\/","url":"https:\/\/startupvalley.news\/de\/gerdaxdoris-online-coaching-business\/","name":"GerdaxDoris: Online Coaching Business Social Media Marketing","isPartOf":{"@id":"https:\/\/startupvalley.news\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/startupvalley.news\/de\/gerdaxdoris-online-coaching-business\/#primaryimage"},"image":{"@id":"https:\/\/startupvalley.news\/de\/gerdaxdoris-online-coaching-business\/#primaryimage"},"thumbnailUrl":"https:\/\/startupvalley.news\/de\/wp-content\/uploads\/sites\/2\/2022\/10\/Barbara-Streit.jpg","datePublished":"2022-11-03T07:20:00+00:00","dateModified":"2026-06-13T08:08:54+00:00","description":"GerdaxDoris: Online Coaching Business \u00fcber Social Media Marketing und Businessaufbau- die richtige Mischung von Intuition und Strategie","breadcrumb":{"@id":"https:\/\/startupvalley.news\/de\/gerdaxdoris-online-coaching-business\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/startupvalley.news\/de\/gerdaxdoris-online-coaching-business\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/startupvalley.news\/de\/gerdaxdoris-online-coaching-business\/#primaryimage","url":"https:\/\/startupvalley.news\/de\/wp-content\/uploads\/sites\/2\/2022\/10\/Barbara-Streit.jpg","contentUrl":"https:\/\/startupvalley.news\/de\/wp-content\/uploads\/sites\/2\/2022\/10\/Barbara-Streit.jpg","width":1200,"height":680,"caption":"GerdaxDoris: Online Coaching Business \u00fcber Social Media Marketing"},{"@type":"BreadcrumbList","@id":"https:\/\/startupvalley.news\/de\/gerdaxdoris-online-coaching-business\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/startupvalley.news\/de\/"},{"@type":"ListItem","position":2,"name":"Du brauchst eine Menge Vertrauen in Dich und viel Gelassenheit"}]},{"@type":"WebSite","@id":"https:\/\/startupvalley.news\/de\/#website","url":"https:\/\/startupvalley.news\/de\/","name":"StartupValley","description":"Startup-News, Funding &amp; Gr\u00fcnder-Interviews","publisher":{"@id":"https:\/\/startupvalley.news\/de\/#organization"},"alternateName":"StartupValley Magazin","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/startupvalley.news\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/startupvalley.news\/de\/#organization","name":"StartupValley Media","url":"https:\/\/startupvalley.news\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/startupvalley.news\/de\/#\/schema\/logo\/image\/","url":"https:\/\/startupvalley.news\/de\/wp-content\/uploads\/sites\/2\/2020\/12\/StartupValley-LOGO-neu-retina.png","contentUrl":"https:\/\/startupvalley.news\/de\/wp-content\/uploads\/sites\/2\/2020\/12\/StartupValley-LOGO-neu-retina.png","width":460,"height":180,"caption":"StartupValley Media"},"image":{"@id":"https:\/\/startupvalley.news\/de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/startupvalleynews","https:\/\/x.com\/startup_valley","https:\/\/www.twitch.tv\/startupvalley","https:\/\/www.linkedin.com\/company\/startupvalleymagazine","https:\/\/www.instagram.com\/startup_valley"]},{"@type":"Person","@id":"https:\/\/startupvalley.news\/de\/#\/schema\/person\/dc9abc71daa8d949d4f257f2e9883e00","name":"StartupValley","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/6436ca57465a88bfa716825ebdd3bc23f850aaaa3a51d16da34504822452fa3a?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/6436ca57465a88bfa716825ebdd3bc23f850aaaa3a51d16da34504822452fa3a?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/6436ca57465a88bfa716825ebdd3bc23f850aaaa3a51d16da34504822452fa3a?s=96&d=mm&r=g","caption":"StartupValley"},"description":"Das StartupValley Magazin ist Europas gro\u00dfes Magazin f\u00fcr Start-ups, Gr\u00fcnder und Entrepreneure. Ihr findet bei uns Tagesaktuelle News zu den neuesten Trends, Technologien und Gesch\u00e4ftsmodellen der internationalen Startup-Szene sowie Interviews mit erfolgreichen Gr\u00fcndern und Investoren.","url":"https:\/\/startupvalley.news\/de\/author\/redaktion\/"}]}},"_links":{"self":[{"href":"https:\/\/startupvalley.news\/de\/wp-json\/wp\/v2\/posts\/91876","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/startupvalley.news\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/startupvalley.news\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/startupvalley.news\/de\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/startupvalley.news\/de\/wp-json\/wp\/v2\/comments?post=91876"}],"version-history":[{"count":1,"href":"https:\/\/startupvalley.news\/de\/wp-json\/wp\/v2\/posts\/91876\/revisions"}],"predecessor-version":[{"id":107701,"href":"https:\/\/startupvalley.news\/de\/wp-json\/wp\/v2\/posts\/91876\/revisions\/107701"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/startupvalley.news\/de\/wp-json\/wp\/v2\/media\/92477"}],"wp:attachment":[{"href":"https:\/\/startupvalley.news\/de\/wp-json\/wp\/v2\/media?parent=91876"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/startupvalley.news\/de\/wp-json\/wp\/v2\/categories?post=91876"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/startupvalley.news\/de\/wp-json\/wp\/v2\/tags?post=91876"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}